{"id":103777,"date":"2022-11-26T20:00:00","date_gmt":"2022-11-26T23:00:00","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=103777"},"modified":"2022-11-26T20:00:00","modified_gmt":"2022-11-26T23:00:00","slug":"cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/","title":{"rendered":"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png\" alt=\"\" class=\"wp-image-103778\"\/><\/a><figcaption>O projeto segue incentivando o h\u00e1bito de ler, dessa vez com a oficina, que visa ampliar o conhecimento das estrat\u00e9gias de leitura pelos mediadores<\/figcaption><\/figure><\/div>\n\n\n\n<p>Em mais uma etapa do projeto Cidadania e Leitura, a Oficina de Promo\u00e7\u00e3o da Leitura foi realizada neste s\u00e1bado (26), na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso (Vila Embratel), com a participa\u00e7\u00e3o de 25 mediadores. A iniciativa \u00e9 desenvolvida pela Sociedade de Amigos das Bibliotecas do Maranh\u00e3o (SAB\/MA), com patroc\u00ednio do Instituto Cultural Vale e apoio da Pastoral do Menor.<\/p>\n\n\n\n<p>&#8220;Seguimos com o trabalho de incentivo ao h\u00e1bito de ler, agora com esta oficina que visa ampliar o conhecimento das estrat\u00e9gias de leitura pelos mediadores, para que possam ser desenvolvidas nas bibliotecas que foram entregues pelo projeto na \u00e1rea Itaqui-Bacanga&#8221;, afirmou Rosa Maria Ferreira Lima, bibliotec\u00e1ria e coordenadora do Cidadania e Leitura.<\/p>\n\n\n\n<p>A Oficina de Promo\u00e7\u00e3o da Leitura foi ministrada pela professora Leoneide Maria Brito Martins, da Universidade Federal do Maranh\u00e3o (UFMA), dando seguimento \u00e0s atividades iniciadas no dia 19, no mesmo espa\u00e7o.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923542.png\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923542.png\" alt=\"\" class=\"wp-image-103779\"\/><\/a><figcaption>Oficina de Promo\u00e7\u00e3o da Leitura foi ministrada pela professora Leoneide Maria Brito Martins, da Universidade Federal do Maranh\u00e3o (UFMA)<\/figcaption><\/figure><\/div>\n\n\n\n<p>Ao final, foi realizada programa\u00e7\u00e3o cultural com crian\u00e7as e jovens da comunidade e atividades de incentivo \u00e0 leitura, com destaque para o Carro Biblioteca da SAB e seu rico acervo de cl\u00e1ssicos da literatura. A a\u00e7\u00e3o ter\u00e1 continuidade na ter\u00e7a-feira (29).<\/p>\n\n\n\n<p><em><strong>Mais parceria<\/strong><\/em><\/p>\n\n\n\n<p>O Cidadania e Leitura ganhou o refor\u00e7o da parceria do projeto Con-fabulando: nos Trilhos da Leitura, desenvolvido pelo N\u00facleo de Produ\u00e7\u00e3o Teoria das Artes, do Anjo da Guarda. A a\u00e7\u00e3o faz parte de um circuito de atividades voltado a fortalecer a promo\u00e7\u00e3o do conhecimento.<\/p>\n\n\n\n<p>Consiste em oficina de leitura, atividades de cria\u00e7\u00e3o liter\u00e1ria e apresenta\u00e7\u00e3o teatral. O objetivo das atividades \u00e9 dinamizar os espa\u00e7os de leitura inaugurados pelo Cidadania e Leitura (Bibliotecas Comunit\u00e1rias Maria Arag\u00e3o, na Vila Bacanga; Luiz Phelipe Andr\u00e9s, na Vila Ariri; e Elis\u00e2ngela Cardoso, na Vila Embratel).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1924222.png\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1924222.png\" alt=\"\" class=\"wp-image-103780\"\/><\/a><figcaption>As atividades foram iniciadas nos dias 21, 22 e 23 deste m\u00eas, na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso, na Vila Embratel<\/figcaption><\/figure><\/div>\n\n\n\n<p>&#8220;O projeto tem o objetivo de divulgar as bibliotecas comunit\u00e1rias da \u00e1rea Itaqui-Bacanga como espa\u00e7o de conhecimento e aprendizado. A a\u00e7\u00e3o consiste no circuito de 10 apresenta\u00e7\u00f5es do espet\u00e1culo &#8216;Cantoria e Correria &#8211; A amea\u00e7a do Exterminador&#8217;, baseado na f\u00e1bula &#8216;A Cigarra e A Formiga&#8221;&#8217;, ressaltou Lewdyson Clay dos Santos e Santos, coordenador do Con-fabulando: nos Trilhos da Leitura.<\/p>\n\n\n\n<p>As atividades foram iniciadas nos dias 21, 22 e 23 deste m\u00eas, na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso. No per\u00edodo de 28 a 30 de novembro, movimentar\u00e1 a Biblioteca Phelipe Andr\u00e9s, na Vila Ariri. Para fechar, nos dias 30 de novembro e 1\u00b0 e 2 de dezembro, ocupar\u00e1 a Biblioteca Comunit\u00e1ria Maria Arag\u00e3o, na Vila Bacanga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em mais uma etapa do projeto Cidadania e Leitura, a Oficina de Promo\u00e7\u00e3o da Leitura foi realizada neste s\u00e1bado (26), [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-103777","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"Em mais uma etapa do projeto Cidadania e Leitura, a Oficina de Promo\u00e7\u00e3o da Leitura foi realizada neste s\u00e1bado (26), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-26T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/\",\"name\":\"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png\",\"datePublished\":\"2022-11-26T23:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/","og_locale":"pt_BR","og_type":"article","og_title":"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso - Daniel Matos","og_description":"Em mais uma etapa do projeto Cidadania e Leitura, a Oficina de Promo\u00e7\u00e3o da Leitura foi realizada neste s\u00e1bado (26), [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/","og_site_name":"Daniel Matos","article_published_time":"2022-11-26T23:00:00+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/","name":"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png","datePublished":"2022-11-26T23:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2022\/11\/Screenshot_20221126-1923182.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/cidadania-e-leitura-promove-oficina-e-programacao-cultural-na-biblioteca-comunitaria-elisangela-cardoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Cidadania e Leitura promove oficina e programa\u00e7\u00e3o cultural na Biblioteca Comunit\u00e1ria Elis\u00e2ngela Cardoso"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/103777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=103777"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/103777\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=103777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=103777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=103777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}