{"id":139810,"date":"2025-02-18T02:27:36","date_gmt":"2025-02-18T05:27:36","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=139810"},"modified":"2025-02-18T02:27:36","modified_gmt":"2025-02-18T05:27:36","slug":"equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/","title":{"rendered":"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3"},"content":{"rendered":"\n<p><em><strong><span class=\"has-inline-color has-vivid-red-color\">Ao todo, ser\u00e3o entregues 180 geladeiras novas aos moradores dos munic\u00edpios<\/span><\/strong><\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png\" alt=\"\" class=\"wp-image-139811\"\/><\/a><figcaption>Geladeiras antigas entregues por clientes da Equatorial Maranh\u00e3o em troca de modelos novos e mais econ\u00f4micos <\/figcaption><\/figure><\/div>\n\n\n\n<p>Os clientes da Equatorial Maranh\u00e3o, nos munic\u00edpios de\u00a0<strong>Imperatriz<\/strong>\u00a0e\u00a0<strong>Cod\u00f3<\/strong>, recebem, durante esta semana, o projeto E+ Geladeira Nova. Esta a\u00e7\u00e3o da distribuidora faz parte do Programa de Efici\u00eancia Energ\u00e9tica da Ag\u00eancia Nacional de Energia El\u00e9trica (PEE\/ANEEL) e visa \u00e0 troca de geladeiras velhas, que consomem mais energia, por modelos novos, mais eficientes e econ\u00f4micos. Para participar, as fam\u00edlias devem estar cadastradas na Tarifa Social de Baixa Renda.<\/p>\n\n\n\n<p>Os cadastros come\u00e7am na ter\u00e7a-feira (18) e quarta-feira (19), para estar apto para concorrer, o cliente deve ser&nbsp;<strong>residente da cidade em que est\u00e1 se cadastrando<\/strong>&nbsp;e&nbsp;<strong>o titular da conta de energia<\/strong>, al\u00e9m disso, \u00e9 necess\u00e1rio levar&nbsp;<strong>o RG, CPF, a \u00faltima fatura de energia quitada e possuir cadastro na Tarifa&nbsp;Social de&nbsp;Energia&nbsp;El\u00e9trica.&nbsp;<\/strong>J\u00e1 o sorteio ser\u00e1 realizado na quinta-feira (20) e a entrega das geladeiras novas ocorrer\u00e1 na sexta-feira (21).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221312.png\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221312.png\" alt=\"\" class=\"wp-image-139812\"\/><\/a><figcaption>Al\u00e9m da troca de geladeiras, a Distribuidora ainda far\u00e1 a\u00e7\u00f5es de cadastro\u00a0e atualiza\u00e7\u00e3o\u00a0na Tarifa Social,\u00a0programa do Governo Federal,\u00a0que oferece descontos de at\u00e9 65% na conta de energia<\/figcaption><\/figure><\/div>\n\n\n\n<p>Em Cod\u00f3,\u00a0ser\u00e3o sorteadas 80 geladeiras, j\u00e1 em Imperatriz,\u00a0ser\u00e3o 100 refrigeradores novos,\u00a0que poder\u00e3o substituir os antigos. Vale ressaltar ainda que o transporte da geladeira antiga at\u00e9 o local da troca, assim como o retorno at\u00e9 a resid\u00eancia, com a geladeira nova, \u00e9 de responsabilidade do consumidor. No ato da entrega, ser\u00e3o repassadas orienta\u00e7\u00f5es sobre o uso correto do novo eletrodom\u00e9stico.<\/p>\n\n\n\n<p><strong>Mais servi\u00e7os oferecidos:<\/strong><\/p>\n\n\n\n<p>Al\u00e9m da troca de geladeiras, a Distribuidora ainda far\u00e1 a\u00e7\u00f5es de cadastro\u00a0e atualiza\u00e7\u00e3o\u00a0na Tarifa Social,\u00a0programa do Governo Federal,\u00a0que oferece descontos de at\u00e9 65% na conta de energia, ser\u00e3o oferecidas tamb\u00e9m negocia\u00e7\u00f5es de d\u00e9bitos conforme a situa\u00e7\u00e3o e o perfil de cada cliente. Os consumidores ainda poder\u00e3o trocar cinco l\u00e2mpadas incandescentes ou fluorescentes por modelos de LED, que podem ser at\u00e9 80% mais econ\u00f4micos.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0222022.png\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0222022.png\" alt=\"\" class=\"wp-image-139813\"\/><\/a><figcaption>Equipe da Equatorial Maranh\u00e3o entrega geladeira nova a cliente contemplada pelo programa <\/figcaption><\/figure><\/div>\n\n\n\n<p>Nos dias 18 e 19 (ter\u00e7a e quarta-feira), a Equatorial Maranh\u00e3o tamb\u00e9m promover\u00e1 um&nbsp;<strong>workshop de barbeiro<\/strong>&nbsp;no munic\u00edpio de&nbsp;<strong>Cod\u00f3<\/strong>. A a\u00e7\u00e3o faz parte do programa&nbsp;<strong>E+ Profissional<\/strong>, iniciativa do Programa de Efici\u00eancia Energ\u00e9tica da ANEEL, e integra os projetos de responsabilidade social da distribuidora. O objetivo \u00e9 capacitar e fomentar oportunidades para jovens e adultos de baixa renda, oferecendo qualifica\u00e7\u00e3o profissional gratuita em todo o estado.<\/p>\n\n\n\n<p><strong>Confira abaixo o calend\u00e1rio completo das a\u00e7\u00f5es:&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>E+ Geladeira Nova<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Cod\u00f3<\/strong><\/p>\n\n\n\n<p>Data: Cadastro \u2013 ter\u00e7a-feira (18) e quarta-feira (19);&nbsp;Sorteio \u2013 quinta-feira (20); Entrega \u2013 sexta-feira (21);<\/p>\n\n\n\n<p>Hor\u00e1rio: 8h \u00e0s 12h e 14h \u00e0s 17h;<\/p>\n\n\n\n<p>Local: Pra\u00e7a S\u00e3o Sebasti\u00e3o, centro de Cod\u00f3<\/p>\n\n\n\n<p><strong>Imperatriz<\/strong><\/p>\n\n\n\n<p>Data: Cadastro \u2013 ter\u00e7a-feira (18) e quarta-feira (19);&nbsp;Sorteio \u2013 quinta-feira (20); Entrega \u2013 sexta-feira (21);<\/p>\n\n\n\n<p>Hor\u00e1rio: 9h \u00e0s 16h;<\/p>\n\n\n\n<p>Local: Centro de Conven\u00e7\u00f5es, localizado na Rua Hermes da Fonseca, Centro<\/p>\n\n\n\n<p><strong>Workshops<\/strong><\/p>\n\n\n\n<p><strong>Cod\u00f3 \u2013 Workshop Barbeiro<\/strong><\/p>\n\n\n\n<p>Data: ter\u00e7a-feira e quarta-feira (18 e 19);<\/p>\n\n\n\n<p>Hor\u00e1rio: 08h \u00e0s 17h;<\/p>\n\n\n\n<p>Local: Pra\u00e7a S\u00e3o Sebasti\u00e3o, centro de Cod\u00f3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao todo, ser\u00e3o entregues 180 geladeiras novas aos moradores dos munic\u00edpios Os clientes da Equatorial Maranh\u00e3o, nos munic\u00edpios de\u00a0Imperatriz\u00a0e\u00a0Cod\u00f3, recebem, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-139810","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3 - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3 - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"Ao todo, ser\u00e3o entregues 180 geladeiras novas aos moradores dos munic\u00edpios Os clientes da Equatorial Maranh\u00e3o, nos munic\u00edpios de\u00a0Imperatriz\u00a0e\u00a0Cod\u00f3, recebem, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T05:27:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/\",\"name\":\"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3 - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png\",\"datePublished\":\"2025-02-18T05:27:36+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3 - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/","og_locale":"pt_BR","og_type":"article","og_title":"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3 - Daniel Matos","og_description":"Ao todo, ser\u00e3o entregues 180 geladeiras novas aos moradores dos munic\u00edpios Os clientes da Equatorial Maranh\u00e3o, nos munic\u00edpios de\u00a0Imperatriz\u00a0e\u00a0Cod\u00f3, recebem, [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/","og_site_name":"Daniel Matos","article_published_time":"2025-02-18T05:27:36+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/","name":"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3 - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png","datePublished":"2025-02-18T05:27:36+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2025\/02\/Screenshot_20250218-0221002.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/equatorial-maranhao-realiza-troca-de-geladeiras-em-imperatriz-e-codo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Equatorial Maranh\u00e3o realiza troca de geladeiras em Imperatriz e Cod\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/139810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=139810"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/139810\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=139810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=139810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=139810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}