{"id":145388,"date":"2025-06-20T10:13:03","date_gmt":"2025-06-20T13:13:03","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=145388"},"modified":"2025-06-20T10:13:05","modified_gmt":"2025-06-20T13:13:05","slug":"publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/","title":{"rendered":"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o"},"content":{"rendered":"\n<p><strong><mark style=\"color:#cf2e2e\" class=\"has-inline-color\">Prestigiaram a abertura os deputados Iracema Vale, Davi Brand\u00e3o, Adelmo Soares, Wellington do Curso, J\u00fanior Fran\u00e7a e Ana do G\u00e1s<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"397\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693-1024x397.jpg\" alt=\"\" class=\"wp-image-145389\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693-1024x397.jpg 1024w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693-300x116.jpg 300w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693-768x297.jpg 768w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg 1420w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Muita gente marcou presen\u00e7a na primeira noite do Arraial da Assembleia e elogiou a organiza\u00e7\u00e3o e a programa\u00e7\u00e3o do espa\u00e7o<\/figcaption><\/figure>\n\n\n\n<p>P\u00fablico numeroso marcou presen\u00e7a na primeira noite do Arraial da Assembleia 2025, aberto nesta quinta-feira (19) pela presidente da Alema, deputada Iracema Vale (PSB), na presen\u00e7a de outros parlamentares e autoridades. Mais uma vez, o p\u00fablico elogiou a organiza\u00e7\u00e3o e a programa\u00e7\u00e3o do espa\u00e7o junino.<\/p>\n\n\n\n<p>Prestigiaram a abertura os deputados Davi Brand\u00e3o (PSB), Adelmo Soares (PSB), Wellington do Curso (Novo), J\u00fanior Fran\u00e7a (PP) e Ana do G\u00e1s (PCdoB). Tamb\u00e9m estavam o deputado federal Rubens J\u00fanior (PT) e o prefeito de Bacabal e presidente da Federa\u00e7\u00e3o dos Munic\u00edpios do Estado do Maranh\u00e3o (Famem), Roberto Costa.<\/p>\n\n\n\n<p>Iracema Vale ressaltou a import\u00e2ncia da festa como um espa\u00e7o democr\u00e1tico de celebra\u00e7\u00e3o e exalta\u00e7\u00e3o \u00e0s ra\u00edzes culturais maranhenses. \u201cA cada ano que passa, nosso S\u00e3o Jo\u00e3o fica melhor, cresce e se fortalece. \u00c9 mais do que uma grande festa popular, j\u00e1 que o turismo, a economia e a rede hoteleira tamb\u00e9m t\u00eam sentido sua for\u00e7a e crescido, impulsionados pelos investimentos feitos pelo governador Carlos Brand\u00e3o, o que \u00e9 maravilhoso, pois, al\u00e9m da festa, que o povo ama, incentivamos a gera\u00e7\u00e3o de renda e impulsionamos a economia. Sejam bem-vindos e aproveitem\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704697-1024x682.jpg\" alt=\"\" class=\"wp-image-145390\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704697-1024x682.jpg 1024w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704697-300x200.jpg 300w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704697-768x512.jpg 768w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704697.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Diversidade de grupos folcl\u00f3ricos marcou primeira noite de festan\u00e7a no Arraial da Assembleia<\/figcaption><\/figure>\n\n\n\n<p><strong>Diversidade cultural<\/strong><\/p>\n\n\n\n<p>O Forr\u00f3 P\u00e9 de Serra foi a primeira atra\u00e7\u00e3o a se apresentar, seguida pela Quadrilha Busca P\u00e9 da Ilha, Bumba Meu Boi D\u2019Itapari, Dan\u00e7a Portuguesa Vira Luzitanos, Boi de Upaon-A\u00e7u, Boi Valente da Ilha e Boi Lendas e Magia. Na sequ\u00eancia, teve Boi de Axix\u00e1, Companhia Vem BB, Boi de Tamarineiro, Dan\u00e7a Country Cora\u00e7\u00e3o de Pe\u00e3o e o Boi de Nina Rodrigues.<\/p>\n\n\n\n<p><strong>Seguran\u00e7a e acessibilidade<\/strong><\/p>\n\n\n\n<p>O p\u00fablico destacou a estrutura montada para garantir seguran\u00e7a e conforto aos visitantes, enfatizando os espa\u00e7os espec\u00edficos para crian\u00e7as, idosos e pessoas com defici\u00eancia.<\/p>\n\n\n\n<p>Outro diferencial, que garante inclus\u00e3o e acessibilidade, foi a instala\u00e7\u00e3o de rampas para cadeirantes ou pessoas com baixa mobilidade. H\u00e1, ainda, mesas e cadeiras nos espa\u00e7os das barracas, al\u00e9m da presen\u00e7a de int\u00e9rpretes de libras durante as apresenta\u00e7\u00f5es.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704709-1024x682.jpg\" alt=\"\" class=\"wp-image-145391\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704709-1024x682.jpg 1024w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704709-300x200.jpg 300w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704709-768x512.jpg 768w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704709.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Grupo de Bumba Meu Boi evolui no tablado de apresenta\u00e7\u00f5es do Arraial da Assembleia<\/figcaption><\/figure>\n\n\n\n<p>\u201cS\u00f3 tenho a louvar essa ideia dos organizadores deste arraial, de garantir o acesso de cadeirantes e deix\u00e1-los mais \u00e0 vontade em um espa\u00e7o como este\u201d, afirmou o servidor p\u00fablico Jos\u00e9 Eus\u00e9bio Ribeiro dos Santos, de 52 anos.<\/p>\n\n\n\n<p>Um espa\u00e7o especial, de frente para o tablado onde evoluem os grupos folcl\u00f3ricos, tamb\u00e9m foi disponibilizado a pessoas com pouca mobilidade e idosos. Um parquinho infantil garantiu a divers\u00e3o da crian\u00e7ada.<\/p>\n\n\n\n<p><strong>PROGRAMA\u00c7\u00c3O DO ARRAIAL DA ASSEMBLEIA<\/strong> &#8211; <strong>SEXTA-FEIRA (20\/06)<\/strong><\/p>\n\n\n\n<p>18h30 \u2013 Boi da Floresta<\/p>\n\n\n\n<p>19h30 \u2013 Boi Estrela dos Len\u00e7\u00f3is<\/p>\n\n\n\n<p>20h30 \u2013 Novilho dos Len\u00e7\u00f3is<\/p>\n\n\n\n<p>21h \u2013 Boi Famos\u00e3o<\/p>\n\n\n\n<p>22h \u2013 Boi da Madre Deus<\/p>\n\n\n\n<p>23h \u2013 Boi da Lua<\/p>\n\n\n\n<p>23h30 \u2013 Companhia Encantar<\/p>\n\n\n\n<p>0h \u2013 Boi Pirilampo<\/p>\n\n\n\n<p>1h \u2013 Boi da Maioba<\/p>\n\n\n\n<p><strong>Domingo \u2013 (dia 22\/06)<\/strong><\/p>\n\n\n\n<p>17h30 \u2013 Paula Nordestina<\/p>\n\n\n\n<p>18h \u2013 Boi Revela\u00e7\u00e3o de S\u00e3o Mar\u00e7al<\/p>\n\n\n\n<p>18h30 \u2013 Boi Barrica<\/p>\n\n\n\n<p>19h \u2013 P\u00e9rola dos Len\u00e7\u00f3is<\/p>\n\n\n\n<p>20h \u2013 Boi de Barbosa de Ros\u00e1rio<\/p>\n\n\n\n<p>21h \u2013 Encanto de S\u00e3o Crist\u00f3v\u00e3o<\/p>\n\n\n\n<p>22h \u2013 Coco Pirin\u00e3&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>22h30 \u2013 Boi de S\u00e3o Sim\u00e3o<\/p>\n\n\n\n<p>23h \u2013 Encanto da Ilha<\/p>\n\n\n\n<p>&nbsp;&nbsp; 0h \u2013 Dan\u00e7a Portuguesa Realeza da Boa Nova<\/p>\n\n\n\n<p>&nbsp;&nbsp; 1h \u2013&nbsp;Boi&nbsp;de&nbsp;Matinha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prestigiaram a abertura os deputados Iracema Vale, Davi Brand\u00e3o, Adelmo Soares, Wellington do Curso, J\u00fanior Fran\u00e7a e Ana do G\u00e1s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-145388","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"Prestigiaram a abertura os deputados Iracema Vale, Davi Brand\u00e3o, Adelmo Soares, Wellington do Curso, J\u00fanior Fran\u00e7a e Ana do G\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T13:13:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T13:13:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1420\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Matos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Matos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/\",\"name\":\"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693-1024x397.jpg\",\"datePublished\":\"2025-06-20T13:13:03+00:00\",\"dateModified\":\"2025-06-20T13:13:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg\",\"width\":1420,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0\",\"name\":\"Daniel Matos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g\",\"caption\":\"Daniel Matos\"},\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/author\/danielmatos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/","og_locale":"pt_BR","og_type":"article","og_title":"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o - Daniel Matos","og_description":"Prestigiaram a abertura os deputados Iracema Vale, Davi Brand\u00e3o, Adelmo Soares, Wellington do Curso, J\u00fanior Fran\u00e7a e Ana do G\u00e1s [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/","og_site_name":"Daniel Matos","article_published_time":"2025-06-20T13:13:03+00:00","article_modified_time":"2025-06-20T13:13:05+00:00","og_image":[{"width":1420,"height":550,"url":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg","type":"image\/jpeg"}],"author":"Daniel Matos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniel Matos","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/","name":"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693-1024x397.jpg","datePublished":"2025-06-20T13:13:03+00:00","dateModified":"2025-06-20T13:13:05+00:00","author":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0"},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/06\/1002704693.jpg","width":1420,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/publico-curte-primeira-noite-no-arraial-da-assembleia-e-elogia-organizacao-e-programacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"P\u00fablico curte primeira noite no Arraial da Assembleia e elogia organiza\u00e7\u00e3o e programa\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0","name":"Daniel Matos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g","caption":"Daniel Matos"},"url":"https:\/\/www.blogsoestado.com\/danielmatos\/author\/danielmatos\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/145388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=145388"}],"version-history":[{"count":1,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/145388\/revisions"}],"predecessor-version":[{"id":145392,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/145388\/revisions\/145392"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=145388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=145388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=145388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}