{"id":146269,"date":"2025-07-15T21:23:55","date_gmt":"2025-07-16T00:23:55","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=146269"},"modified":"2025-07-15T21:23:59","modified_gmt":"2025-07-16T00:23:59","slug":"iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/","title":{"rendered":"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019"},"content":{"rendered":"\n<p><strong><mark style=\"color:#cf2e2e\" class=\"has-inline-color\">A iniciativa tem como foco o fortalecimento dos pequenos neg\u00f3cios e o desenvolvimento do ambiente empreendedor<\/mark><\/strong> <strong><mark style=\"color:#cf2e2e\" class=\"has-inline-color\">maranhense<\/mark><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"397\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233-1024x397.jpg\" alt=\"\" class=\"wp-image-146270\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233-1024x397.jpg 1024w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233-300x116.jpg 300w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233-768x297.jpg 768w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg 1420w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Iracema Vale reiterou o compromisso da Assembleia Legislativa com iniciativas que valorizam o empreendedorismo nos munic\u00edpios<\/figcaption><\/figure>\n\n\n\n<p>A presidente da Assembleia Legislativa do Maranh\u00e3o, deputada Iracema Vale (PSB), participou, nesta ter\u00e7a-feira (8), da abertura do \u2018Transformar Juntos\u2019, evento promovido pelo Governo do Estado em parceria com o Sebrae, com foco no fortalecimento dos pequenos neg\u00f3cios e no desenvolvimento do ambiente empreendedor maranhense. O evento foi comandado pelo governador Carlos Brand\u00e3o e contou tamb\u00e9m com a participa\u00e7\u00e3o do presidente do Conselho Deliberativo Estadual do Sebrae\/MA, Celso Gon\u00e7alo, e do presidente da Federa\u00e7\u00e3o dos Munic\u00edpios do Maranh\u00e3o (Famem), Roberto Costa, entre outras autoridades.<\/p>\n\n\n\n<p>Na ocasi\u00e3o, a chefe do Legislativo maranhense ressaltou que sua participa\u00e7\u00e3o refor\u00e7a o compromisso da Assembleia Legislativa com o desenvolvimento econ\u00f4mico do Maranh\u00e3o, especialmente com iniciativas que valorizam o empreendedorismo nos munic\u00edpios.<\/p>\n\n\n\n<p>\u201cEstou aqui hoje n\u00e3o apenas como presidente da Assembleia Legislativa do Maranh\u00e3o, mas tamb\u00e9m como algu\u00e9m que conhece, na pele, a realidade dos parlamentos municipais. Fui vereadora por dois mandatos e prefeita por mais dois, na cidade de Urbano Santos. Sei o quanto \u00e9 desafiador e, ao mesmo tempo, transformador, fazer pol\u00edtica p\u00fablica a partir da ponta, do ch\u00e3o do munic\u00edpio, onde a vida de fato acontece\u201d, destacou Iracema Vale.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970237-1024x683.jpg\" alt=\"\" class=\"wp-image-146271\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970237-1024x683.jpg 1024w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970237-300x200.jpg 300w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970237-768x512.jpg 768w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970237.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Governador Carlos Brand\u00e3o, Iracema Vale e representantes de diversas institui\u00e7\u00f5es para debater pol\u00edticas p\u00fablicas que fomentem oportunidades para pequenos empreendedores<\/figcaption><\/figure>\n\n\n\n<p>O encontro reuniu ainda gestores p\u00fablicos e representantes de diversas institui\u00e7\u00f5es para debater pol\u00edticas p\u00fablicas e iniciativas que impulsionem a economia local e fomentem oportunidades para os pequenos empreendedores. O ato contou tamb\u00e9m com a participa\u00e7\u00e3o da vice-prefeita de S\u00e3o Lu\u00eds, Esm\u00eania Miranda.<\/p>\n\n\n\n<p><strong>Empreendedorismo<\/strong><\/p>\n\n\n\n<p>O \u2018Transformar Juntos 2025\u2019 tem como objetivo promover a transforma\u00e7\u00e3o dos territ\u00f3rios maranhenses por meio da integra\u00e7\u00e3o entre gest\u00e3o p\u00fablica, empreendedorismo e inova\u00e7\u00e3o, com foco no desenvolvimento sustent\u00e1vel, inclusivo e competitivo em todas as regi\u00f5es do estado.<\/p>\n\n\n\n<p>Durante o evento, o governador Carlos Brand\u00e3o destacou a relev\u00e2ncia das parcerias institucionais para garantir que as a\u00e7\u00f5es de desenvolvimento cheguem de forma mais \u00e1gil e eficiente aos munic\u00edpios maranhenses. \u201cHoje, estamos vivendo um momento de moderniza\u00e7\u00e3o e o Maranh\u00e3o n\u00e3o pode ficar para tr\u00e1s. Por isso, estamos firmando essa parceria com a Federa\u00e7\u00e3o dos Munic\u00edpios, com a Assembleia Legislativa e com o Sebrae, para que possamos chegar mais r\u00e1pido e com mais efici\u00eancia na ponta\u201d, frisou.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970248-1024x683.jpg\" alt=\"\" class=\"wp-image-146272\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970248-1024x683.jpg 1024w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970248-300x200.jpg 300w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970248-768x512.jpg 768w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970248.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Iracema Vale disse que conhece, na pele, a realidade dos parlamentos municipais e o qu\u00e3o transformador \u00e9 fazer pol\u00edtica p\u00fablica a partir da ponta<\/figcaption><\/figure>\n\n\n\n<p>O presidente do Conselho Deliberativo Estadual do Sebrae Maranh\u00e3o, Celso Gon\u00e7alo, afirmou que o \u2018Transformar Juntos\u2019 marca o in\u00edcio de um novo ciclo para o empreendedorismo no estado, ao incentivar iniciativas que geram oportunidades, promovem a inova\u00e7\u00e3o e colocam os munic\u00edpios como protagonistas do desenvolvimento.<\/p>\n\n\n\n<p>Segundo ele, o evento refor\u00e7a a import\u00e2ncia da inova\u00e7\u00e3o, do empreendedorismo e do compromisso social como instrumentos para transformar realidades e melhorar a vida das pessoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A iniciativa tem como foco o fortalecimento dos pequenos neg\u00f3cios e o desenvolvimento do ambiente empreendedor maranhense A presidente da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-146269","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019 - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019 - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"A iniciativa tem como foco o fortalecimento dos pequenos neg\u00f3cios e o desenvolvimento do ambiente empreendedor maranhense A presidente da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-16T00:23:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T00:23:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1420\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Matos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Matos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/\",\"name\":\"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019 - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233-1024x397.jpg\",\"datePublished\":\"2025-07-16T00:23:55+00:00\",\"dateModified\":\"2025-07-16T00:23:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg\",\"width\":1420,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0\",\"name\":\"Daniel Matos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g\",\"caption\":\"Daniel Matos\"},\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/author\/danielmatos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019 - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/","og_locale":"pt_BR","og_type":"article","og_title":"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019 - Daniel Matos","og_description":"A iniciativa tem como foco o fortalecimento dos pequenos neg\u00f3cios e o desenvolvimento do ambiente empreendedor maranhense A presidente da [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/","og_site_name":"Daniel Matos","article_published_time":"2025-07-16T00:23:55+00:00","article_modified_time":"2025-07-16T00:23:59+00:00","og_image":[{"width":1420,"height":550,"url":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg","type":"image\/jpeg"}],"author":"Daniel Matos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniel Matos","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/","name":"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019 - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233-1024x397.jpg","datePublished":"2025-07-16T00:23:55+00:00","dateModified":"2025-07-16T00:23:59+00:00","author":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0"},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/07\/1002970233.jpg","width":1420,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/iracema-vale-reafirma-compromisso-com-o-fortalecimento-dos-pequenos-negocios-durante-abertura-do-transformar-juntos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Iracema Vale reafirma compromisso com o fortalecimento dos pequenos neg\u00f3cios durante abertura do \u2018Transformar Juntos\u2019"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0","name":"Daniel Matos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g","caption":"Daniel Matos"},"url":"https:\/\/www.blogsoestado.com\/danielmatos\/author\/danielmatos\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/146269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=146269"}],"version-history":[{"count":1,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/146269\/revisions"}],"predecessor-version":[{"id":146273,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/146269\/revisions\/146273"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=146269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=146269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=146269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}