{"id":150548,"date":"2025-11-05T10:02:06","date_gmt":"2025-11-05T13:02:06","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=150548"},"modified":"2025-11-05T10:02:08","modified_gmt":"2025-11-05T13:02:08","slug":"marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/","title":{"rendered":"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"759\" height=\"500\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg\" alt=\"\" class=\"wp-image-150550\" srcset=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg 759w, https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1-300x198.jpg 300w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><figcaption class=\"wp-element-caption\">O vereador Marlon Bot\u00e3o preside a Comiss\u00e3o Especial do Passe Livre na C\u00e2mara Municipal<\/figcaption><\/figure>\n\n\n\n<p>A equipe da Ag\u00eancia C\u00e2mara&nbsp;conversou nesta ter\u00e7a-feira, 04, com o vereador Marlon Bot\u00e3o Filho (PSB), sobre a implanta\u00e7\u00e3o do Passe Livre Estudantil em S\u00e3o Lu\u00eds.&nbsp;O artigo faz parte de uma&nbsp;s\u00e9rie de entrevistas que a Comunica\u00e7\u00e3o da Casa realizar\u00e1 com os parlamentares que presidem comiss\u00f5es.<\/p>\n\n\n\n<p id=\"E121\">\u00c9 o caso do vereador Marlon Bot\u00e3o, que comanda a Comiss\u00e3o Especial do Passe Livre na C\u00e2mara Municipal.&nbsp;O parlamentar&nbsp;afirmou que o passe livre garante direitos ligados \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o.<\/p>\n\n\n\n<p id=\"E127\">No bate-papo,&nbsp;Bot\u00e3o&nbsp;cita duas raz\u00f5es para a necessidade imediata de implementar a proposta.&nbsp;A&nbsp;primeira&nbsp;\u00e9 a luta contra a evas\u00e3o escolar, e&nbsp;a&nbsp;segunda&nbsp;\u00e9 a necessidade de investir em educa\u00e7\u00e3o para que os jovens possam ter um futuro mais promissor.<\/p>\n\n\n\n<p id=\"E141\">O vereador tamb\u00e9m falou sobre a visita que o colegiado fez a Fortaleza em busca de experi\u00eancias para implementar o passe livre na cidade. Na capital cearense, o passe livre implementado em 2023 tem um custo anual de R$ 23 milh\u00f5es e beneficia 283 mil estudantes que usam a carteira estudantil.<\/p>\n\n\n\n<p id=\"E145\">O montante \u00e9 significativamente menor do que os R$ 50 milh\u00f5es que a Prefeitura de S\u00e3o Lu\u00eds desembolsou apenas em fevereiro deste ano para subsidiar empresas de \u00f4nibus. Marlon comentou essa disparidade e assegurou que a capital maranhense apresenta uma situa\u00e7\u00e3o financeira s\u00f3lida o suficiente para custear o passe livre.<\/p>\n\n\n\n<p id=\"E151\">Confira a entrevista completa:<\/p>\n\n\n\n<p id=\"E155\"><strong>Ag\u00eancia C\u00e2mara \u2013&nbsp;A maioria dos eleitores da capital maranhense respondeu&nbsp;sim ao Passe Livre Estudantil durante o primeiro turno das elei\u00e7\u00f5es de 2024. Com o resultado, a gratuidade do transporte p\u00fablico para estudantes foi levada \u00e0 C\u00e2mara Municipal em 2025. Como a implanta\u00e7\u00e3o desta importante pol\u00edtica p\u00fablica vem sendo conduzida pela Casa?<\/strong><\/p>\n\n\n\n<p id=\"E161\"><strong>Marlon Bot\u00e3o<\/strong>&nbsp;\u2013&nbsp;A C\u00e2mara&nbsp;de S\u00e3o Lu\u00eds&nbsp;criou uma comiss\u00e3o especial com o objetivo de elaborar uma proposta coletiva, acess\u00edvel e com garantias jur\u00eddicas e or\u00e7ament\u00e1rias. O objetivo \u00e9 enviar o relat\u00f3rio ao Executivo Municipal para viabilizar a implementa\u00e7\u00e3o do passe livre estudantil. Portanto, em resposta ao desejo popular, a Casa estabeleceu esse colegiado, que est\u00e1 em di\u00e1logo com o Poder Judici\u00e1rio, com o Poder Executivo e com a diversidade partid\u00e1ria, pol\u00edtica e plural do Parlamento Municipal. O objetivo \u00e9 fazer com que essa importante pol\u00edtica p\u00fablica se torne realidade, reconhecendo que \u00e9 uma mat\u00e9ria de iniciativa exclusiva do Executivo para o Legislativo Municipal.<\/p>\n\n\n\n<p id=\"E166\"><strong>AG \u2013 Vereador, o senhor define o Passe Livre Estudantil como um \u201cdireito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o\u201d. Pode explicar o que isso significa na pr\u00e1tica, especialmente para as&nbsp;popula\u00e7\u00f5es mais vulner\u00e1veis de S\u00e3o Lu\u00eds?<\/strong><\/p>\n\n\n\n<p id=\"E170\"><strong>MB<\/strong>&nbsp;\u2013&nbsp;A implementa\u00e7\u00e3o do passe-livre estudantil \u00e9 uma garantia de direitos. \u00c9 uma forma de fortalecer a educa\u00e7\u00e3o na nossa cidade, combatendo a evas\u00e3o escolar. \u00c9 uma pol\u00edtica de transfer\u00eancia de renda, fazendo com que hoje seja gasto com a passagem do estudante.<\/p>\n\n\n\n<p id=\"E175\"><strong>AG \u2013 A C\u00e2mara Municipal criou a&nbsp;Comiss\u00e3o Especial do Passe Livre Estudantil com o objetivo de avaliar a possibilidade de implementar esse benef\u00edcio na capital. O grupo j\u00e1 realizou algum estudo de viabilidade t\u00e9cnica, financeira e jur\u00eddica para a efetiva\u00e7\u00e3o da pol\u00edtica p\u00fablica?<\/strong><\/p>\n\n\n\n<p id=\"E180\"><strong>MB<\/strong>&nbsp;\u2013&nbsp;A comiss\u00e3o,&nbsp;que busca a implementa\u00e7\u00e3o do passivo estudantil com muita responsabilidade t\u00e9cnica,&nbsp;tem dialogado e buscado os dados reais e oficiais. Com isso, a gente dialoga com o sindicato da empresa do transporte. Tamb\u00e9m estamos dialogando com a secretaria municipal de tr\u00e2nsito e transporte para que os dados oficiais possam ser levantados a fim de que a gente consiga ter o estudo t\u00e9cnico mais aproximado do que \u00e9 a&nbsp;realidade, &nbsp;a&nbsp;fim de que n\u00f3s consigamos ter uma ideia do arcabou\u00e7o financeiro e fiscal para a implementa\u00e7\u00e3o do passivo estudantil, entendendo que essa importante medida precisa estar inclu\u00edda no or\u00e7amento da cidade. Ent\u00e3o, n\u00f3s temos buscado fazer esses di\u00e1logos e a capta\u00e7\u00e3o de dados oficiais.<\/p>\n\n\n\n<p id=\"E195\"><strong>AG \u2013 Os membros do colegiado visitaram algumas capitais que j\u00e1 implementaram o Passe Livre Estudantil no Pa\u00eds, como S\u00e3o Paulo (SP), Rio de Janeiro (RJ) e Fortaleza (CE). Quais experi\u00eancias adquiriram durante essas agendas de compromissos?<\/strong><\/p>\n\n\n\n<p id=\"E199\"><strong>MB<\/strong>&nbsp;\u2013&nbsp;A comiss\u00e3o, buscando entender como \u00e9 que funciona a realidade do Passe Livre em outros locais, visitou a cidade de Fortaleza, sendo uma das refer\u00eancias no Nordeste na implementa\u00e7\u00e3o do Passe Livre estudantil. Entendendo que, quando h\u00e1 um sentimento positivo na inclus\u00e3o dos mais vulner\u00e1veis, dos mais pobres no or\u00e7amento da cidade, voc\u00ea tem bons dados, como o aumento de passageiros, o aumento de presen\u00e7a na sala de aula&nbsp;e tamb\u00e9m&nbsp;na transfer\u00eancia da economia mista,&nbsp;no que se tange ao custo que outrora era utilizado para o transporte e que retornou para a cesta b\u00e1sica, para a seguran\u00e7a alimentar.<\/p>\n\n\n\n<p id=\"E210\">Ent\u00e3o, de fato, Fortaleza foi visitada pela comiss\u00e3o, onde a gente p\u00f4de perceber que os avan\u00e7os reais na educa\u00e7\u00e3o e no transporte foram garantidos com a implementa\u00e7\u00e3o do passe livre estudantil. Ent\u00e3o, com certeza, foi muito proveitoso e, juntos,&nbsp;a gente vai poder avan\u00e7ar nesse sentido, entendendo que essa importante a\u00e7\u00e3o pode, precisa e merece ter uma seguran\u00e7a jur\u00eddica or\u00e7ament\u00e1ria que, em outras capitais, j\u00e1 existe.<\/p>\n\n\n\n<p id=\"E216\"><strong>AG \u2013 Estimativas divulgadas pelo jornal Di\u00e1rio do Nordeste apontam&nbsp;que o passe livre estudantil em Fortaleza custa R$ 23 milh\u00f5es por ano. O valor \u00e9 bem inferior aos R$ 50 milh\u00f5es que a Prefeitura de S\u00e3o Lu\u00eds pagou em fevereiro para subsidiar empresas de \u00f4nibus. Levando em conta essa disparidade, seria poss\u00edvel dizer que a capital maranhense teria condi\u00e7\u00f5es adequadas para implantar essa pol\u00edtica p\u00fablica?<\/strong><\/p>\n\n\n\n<p id=\"E224\"><strong>MB<\/strong>&nbsp;\u2013&nbsp;S\u00e3o Lu\u00eds vive um momento fiscal financeiro muito positivo, j\u00e1 entra para o seu terceiro ano tendo super\u00e1vit financeiro, ent\u00e3o S\u00e3o Lu\u00eds tem sa\u00fade or\u00e7ament\u00e1ria para implantar essa importante medida que \u00e9 o passivo estudantil. Agora,&nbsp;basta que se haja um entendimento entre o poder p\u00fablico, o sindicato das empresas de transporte,&nbsp;e&nbsp;uma m\u00e3o conciliadora,&nbsp;no sentido da implementa\u00e7\u00e3o. Entendendo que essa&nbsp;a\u00e7\u00e3o&nbsp;depende \u00fanica e exclusivamente da iniciativa do Executivo Municipal, que \u00e9 o poder concedente para as linhas de transporte, para as empresas&nbsp;com s\u00f3cios e onde&nbsp;se&nbsp;ordenam&nbsp;as despesas da cidade.<\/p>\n\n\n\n<p id=\"E245\"><strong>AG \u2013 Existe alguma sugest\u00e3o ou proposta em an\u00e1lise que visa romper com o modelo tradicional de financiamento do transporte p\u00fablico. Como o senhor avalia uma mudan\u00e7a de paradigma que visa transferir o custeio do usu\u00e1rio individual para um fundo coletivo?&nbsp;<\/strong><\/p>\n\n\n\n<p id=\"E249\"><strong>MB&nbsp;<\/strong>\u2013&nbsp;&nbsp;Em&nbsp;outras capitais j\u00e1 existe a taxa\u00e7\u00e3o das grandes empresas no que tange ao transporte. Portanto, \u00e9 necess\u00e1rio que S\u00e3o Lu\u00eds atualize sua pol\u00edtica de taxa\u00e7\u00e3o e busque avan\u00e7os nos fundos de recolhimento do transporte.&nbsp;Esses fundos precisam se modernizar e compreender que, devido ao super\u00e1vit financeiro, \u00e9 vi\u00e1vel destinar recursos para outras aloca\u00e7\u00f5es or\u00e7ament\u00e1rias. Isso garantir\u00e1 a implementa\u00e7\u00e3o do passivo estudantil, uma importante iniciativa de pol\u00edtica p\u00fablica.&nbsp;Ent\u00e3o, de fato, sa\u00fade or\u00e7ament\u00e1ria tem, basta que se tenha um entendimento jur\u00eddico, t\u00e9cnico e, principalmente do ponto de vista pol\u00edtico, o sentimento de fazer.<\/p>\n\n\n\n<p id=\"E264\"><strong>AG \u2013 Quais seriam as vantagens do Passe Livre? Como essa pol\u00edtica p\u00fablica pode elevar o desempenho escolar e a situa\u00e7\u00e3o financeira das fam\u00edlias?&nbsp;<\/strong><\/p>\n\n\n\n<p id=\"E272\"><strong>MB&nbsp;<\/strong>\u2013 &nbsp;Como&nbsp;mencionei, creio que a implementa\u00e7\u00e3o desta relevante pol\u00edtica p\u00fablica ser\u00e1 uma garantia de direitos. Trata-se de uma estrat\u00e9gia para refor\u00e7ar a educa\u00e7\u00e3o em nossa cidade e combater a evas\u00e3o escolar. Al\u00e9m disso, a medida tamb\u00e9m ser\u00e1 um programa de transfer\u00eancia de renda, que resultar\u00e1 na economia de gasto atual com a passagem do estudante.<\/p>\n\n\n\n<p id=\"E278\"><strong>AG \u2013 A Frente do Passe Livre acionou a Prefeitura de S\u00e3o Lu\u00eds para que seja implementado o passe livre para estudantes da capital. Agora, num prazo de 30 dias, tanto a Prefeitura quanto a MOB (que \u00e9 respons\u00e1vel pelo transporte semiurbano) devem se manifestar na a\u00e7\u00e3o. No seu ponto de vista, como essa pode contribuir nesse debate?<\/strong><\/p>\n\n\n\n<p id=\"E282\"><strong>MB<\/strong>&nbsp;\u2013&nbsp;De fato, toda iniciativa&nbsp;\u00e9 v\u00e1lida no que tange a ajudar para a implementa\u00e7\u00e3o do Partido Estudantil,&nbsp;e \u00e9 importante que n\u00f3s possamos construir um equil\u00edbrio financeiro, t\u00e9cnico&nbsp;e&nbsp;jur\u00eddico. Tendo a participa\u00e7\u00e3o fortemente do Minist\u00e9rio P\u00fablico&nbsp;e&nbsp;dos \u00f3rg\u00e3os de controle&nbsp;para que a medida seja efetivada.<\/p>\n\n\n\n<p>Ent\u00e3o, de fato, existe essa a\u00e7\u00e3o. A\u00a0comiss\u00e3o ir\u00e1 acompanhar e buscar ajudar no di\u00e1logo com o Executivo Municipal para que essa importante a\u00e7\u00e3o possa sair do papel.<\/p>\n\n\n\n<p><strong>Fonte: <\/strong>Isa\u00edas Rocha\/Ag\u00eancia C\u00e2mara<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe da Ag\u00eancia C\u00e2mara&nbsp;conversou nesta ter\u00e7a-feira, 04, com o vereador Marlon Bot\u00e3o Filho (PSB), sobre a implanta\u00e7\u00e3o do Passe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-150548","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"A equipe da Ag\u00eancia C\u00e2mara&nbsp;conversou nesta ter\u00e7a-feira, 04, com o vereador Marlon Bot\u00e3o Filho (PSB), sobre a implanta\u00e7\u00e3o do Passe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T13:02:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T13:02:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"759\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Matos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Matos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/\",\"name\":\"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg\",\"datePublished\":\"2025-11-05T13:02:06+00:00\",\"dateModified\":\"2025-11-05T13:02:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg\",\"width\":759,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0\",\"name\":\"Daniel Matos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g\",\"caption\":\"Daniel Matos\"},\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/author\/danielmatos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o - Daniel Matos","og_description":"A equipe da Ag\u00eancia C\u00e2mara&nbsp;conversou nesta ter\u00e7a-feira, 04, com o vereador Marlon Bot\u00e3o Filho (PSB), sobre a implanta\u00e7\u00e3o do Passe [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/","og_site_name":"Daniel Matos","article_published_time":"2025-11-05T13:02:06+00:00","article_modified_time":"2025-11-05T13:02:08+00:00","og_image":[{"width":759,"height":500,"url":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg","type":"image\/jpeg"}],"author":"Daniel Matos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniel Matos","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/","name":"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg","datePublished":"2025-11-05T13:02:06+00:00","dateModified":"2025-11-05T13:02:08+00:00","author":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0"},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-content\/uploads\/sites\/2\/2025\/11\/1004175816-1.jpg","width":759,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/marlon-botao-diz-que-passe-livre-estudantil-e-direito-a-mobilidade-e-a-educacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Marlon Bot\u00e3o diz que passe livre estudantil \u00e9 direito \u00e0 mobilidade e \u00e0 educa\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/9a209d407cd45631f131e1285b661bb0","name":"Daniel Matos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f26c36ee355da19a257f0dfef43952a2588b324ca35d6719e859fe338ac0392?s=96&d=mm&r=g","caption":"Daniel Matos"},"url":"https:\/\/www.blogsoestado.com\/danielmatos\/author\/danielmatos\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/150548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=150548"}],"version-history":[{"count":1,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/150548\/revisions"}],"predecessor-version":[{"id":150551,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/150548\/revisions\/150551"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=150548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=150548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=150548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}