{"id":52840,"date":"2018-07-01T10:54:04","date_gmt":"2018-07-01T13:54:04","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=52840"},"modified":"2018-07-01T10:54:04","modified_gmt":"2018-07-01T13:54:04","slug":"prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/","title":{"rendered":"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado"},"content":{"rendered":"<figure id=\"attachment_52841\" aria-describedby=\"caption-attachment-52841\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-52841\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><figcaption id=\"caption-attachment-52841\" class=\"wp-caption-text\">Weverton e o deputado estadual Andr\u00e9 Fufuca com o prefeito Juran e o filho Ciro Neto, pr\u00e9-candidato a deputado estadual<\/figcaption><\/figure>\n<p>Diante de lideran\u00e7as pol\u00edticas de 27 munic\u00edpios, em sua maioria, das regi\u00f5es Central, do M\u00e9dio Sert\u00e3o e Baixo Parna\u00edba, o prefeito de Presidente Dutra, Juran Carvalho (PP) declarou apoio as pr\u00e9-candidaturas de Weverton ao Senado, Ciro Neto (PP) a deputado estadual e ao deputado federal Andr\u00e9 Fufuca (PP), que concorre \u00e0 reelei\u00e7\u00e3o, durante um jantar de comemora\u00e7\u00e3o pelos 74 anos da cidade na \u00faltima quinta-feira. \u201cHoje, incondicionalmente, Weverton \u00e9 nosso pr\u00e9-candidato ao Senado\u201d, afirmou o prefeito.<\/p>\n<figure id=\"attachment_52842\" aria-describedby=\"caption-attachment-52842\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-52842\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton2.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><figcaption id=\"caption-attachment-52842\" class=\"wp-caption-text\">Weverton agradeceu apoio do prefeito de Presidente Dutra e do seu grupo pol\u00edtico<\/figcaption><\/figure>\n<p>Ciro Neto tamb\u00e9m anunciou seu apoio ao projeto de Weverton ao Senado. \u201cEntendemos que a sua for\u00e7a, sua juventude e a sua habilidade pol\u00edtica, somadas a tudo que tem feito e ao que ainda pode trazer ao Maranh\u00e3o, faz com que estejamos junto dele no seu projeto ao Senado\u201d, garantiu.<\/p>\n<p>Weverton agradeceu o apoio e ressaltou a import\u00e2ncia de as lideran\u00e7as reunirem-se em torno de um projeto coletivo e acrescentou que n\u00e3o tem d\u00favida de que, eleito, Ciro ir\u00e1 ajudar ao Maranh\u00e3o. \u201cPrecisamos de mais protagonismo na busca por pol\u00edticas p\u00fablicas importantes para ajudar na melhoraria de vida das pessoas e tenho certeza que esse grupo est\u00e1 comprometido com essa miss\u00e3o aqui em Presidente Dutra\u201d.<\/p>\n<p><strong>Festa<\/strong><\/p>\n<figure id=\"attachment_52843\" aria-describedby=\"caption-attachment-52843\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-52843\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton3.jpg\" alt=\"\" width=\"640\" height=\"442\" \/><figcaption id=\"caption-attachment-52843\" class=\"wp-caption-text\">Andr\u00e9 Fufuca, Weverton, Ciro Neto e Juran Carvalho de bra\u00e7os dados em sinal de uni\u00e3o pela vit\u00f3ria<\/figcaption><\/figure>\n<p>O deputado Weverton participou do encerramento das festividades de anivers\u00e1rio da cidade, na Pra\u00e7a S\u00e3o Sebasti\u00e3o. No \u00faltimo domingo Weverton tamb\u00e9m esteve no munic\u00edpio, onde participou da 6\u00aa Cavalgada de Presidente Dutra, que marcou o in\u00edcio das comemora\u00e7\u00f5es e levou centenas de pessoas para as ruas da cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diante de lideran\u00e7as pol\u00edticas de 27 munic\u00edpios, em sua maioria, das regi\u00f5es Central, do M\u00e9dio Sert\u00e3o e Baixo Parna\u00edba, o [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52840","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"Diante de lideran\u00e7as pol\u00edticas de 27 munic\u00edpios, em sua maioria, das regi\u00f5es Central, do M\u00e9dio Sert\u00e3o e Baixo Parna\u00edba, o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-01T13:54:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/\",\"name\":\"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg\",\"datePublished\":\"2018-07-01T13:54:04+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado - Daniel Matos","og_description":"Diante de lideran\u00e7as pol\u00edticas de 27 munic\u00edpios, em sua maioria, das regi\u00f5es Central, do M\u00e9dio Sert\u00e3o e Baixo Parna\u00edba, o [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/","og_site_name":"Daniel Matos","article_published_time":"2018-07-01T13:54:04+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/","name":"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg","datePublished":"2018-07-01T13:54:04+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/07\/juran-weverton.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-de-presidente-dutra-declara-apoio-a-pre-candidatura-de-weverton-ao-senado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Prefeito de presidente Dutra declara apoio \u00e0 pr\u00e9-candidatura de Weverton ao Senado"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/52840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=52840"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/52840\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=52840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=52840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=52840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}