{"id":54154,"date":"2018-08-10T10:13:20","date_gmt":"2018-08-10T13:13:20","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=54154"},"modified":"2018-08-10T10:13:20","modified_gmt":"2018-08-10T13:13:20","slug":"associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/","title":{"rendered":"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o &#8220;levianas&#8221; e &#8220;ferem a democracia e a honra da magistratura brasileira&#8221;"},"content":{"rendered":"<figure id=\"attachment_54157\" aria-describedby=\"caption-attachment-54157\" style=\"width: 450px\" class=\"wp-caption alignright\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-54157\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg\" alt=\"\" width=\"450\" height=\"291\" \/><figcaption id=\"caption-attachment-54157\" class=\"wp-caption-text\">Ju\u00edza Anelise Nogueira Reginato garante que &#8220;decidiu de acordo com as leis, com as provas e com a minha convic\u00e7\u00e3o&#8221;<\/figcaption><\/figure>\n<p>A Associa\u00e7\u00e3o Nacional dos Magistrados Estaduais (Anamages) fez uma defesa incisiva da ju\u00edza Anelise Nogueira Reginato, atacada covardemente pelo grupo pol\u00edtico de Fl\u00e1vio Dino (PCdoB) e por internautas partid\u00e1rios do comunista ap\u00f3s proferir uma decis\u00e3o, no \u00faltimo dia 6, que cassou o prefeito de Coroat\u00e1, Luiz da Amovelar Filho, seu vice, Domingos Alberto Alves de Sousa, e tornou ambos ineleg\u00edveis por oito anos, pena estendida ao governador do Maranh\u00e3o e ao ex-secret\u00e1rio de Estado da Comunica\u00e7\u00e3o Social e Assuntos Pol\u00edticos e atual candidato a deputado federal M\u00e1rcio Jerry (PCdoB). Os quatro foram condenados por abuso de poder econ\u00f4mico, pol\u00edtico e administrativo por condutas vedadas na campanha \u00e0 Prefeitura de Coroat\u00e1, em 2016, quando o governo estadual teria favorecido com obras do programa &#8220;Mais Asfalto&#8221; o ent\u00e3o candidato Luiz da Amovelar Filho, que acabou vencendo a elei\u00e7\u00e3o.<\/p>\n<p>Em nota p\u00fablica emitida na noite dessa quinta-feira (9), A Anamages repudiou as declara\u00e7\u00f5es de Fl\u00e1vio Dino, as quais classificou\u00a0como &#8220;levianas&#8221;.\u00a0Assinado pelo presidente da entidade,\u00a0Magid Nauef L\u00e1uar, o documento alerta que tais atos ferem a democracia e a honra da magistratura brasileira. A nota \u00e9 uma rea\u00e7\u00e3o da Anamages a postagens indignadas do comunista em redes sociais e a afirma\u00e7\u00f5es feitas por ele em entrevistas que concedeu para comentar a decis\u00e3o.<\/p>\n<p>Transtornado, o comunista chegou a chamar a decis\u00e3o da ju\u00edza de factoide e, na tentativa in\u00fatil de tranquilizar seus aliados pol\u00edticos e seu eleitorado, afirmou que a condena\u00e7\u00e3o n\u00e3o produziria efeito algum. No auge da revolta, Dino insinuou que a magistrada assumiu postura partid\u00e1ria, no que a ju\u00edza rebateu prontamente: &#8220;&#8221;Decidi de acordo com as leis, com as provas e com a minha convic\u00e7\u00e3o. N\u00e3o tenho partido pol\u00edtico.&#8221;<\/p>\n<p>A Anamages ressaltou que n\u00e3o admite que magistrados sejam alvos de amea\u00e7as e persegui\u00e7\u00f5es pol\u00edticas, sob quaisquer circunst\u00e2ncias, e anunciou que proceder\u00e1 a imediata instaura\u00e7\u00e3o de procedimento para apurar tais fatos.<\/p>\n<p>Segue a nota, na \u00edntegra:<\/p>\n<p><em>A Associa\u00e7\u00e3o Nacional dos Magistrados Estaduais (ANAMAGES), representada pelo seu Presidente, o Juiz de Direito Magid Nauef L\u00e1uar, e por delibera\u00e7\u00e3o dos membros de sua Diretoria, vem a p\u00fablico desagravar e manifestar o seu irrestrito apoio \u00e0 Ju\u00edza Anelise Nogueira Reginato, da 8\u00aa Zona Eleitoral do Tribunal Regional Eleitoral do Estado do Maranh\u00e3o (TRE\/MA), em face dos ataques covardes que vem sofrendo, desde a \u00faltima quarta-feira (8). Na ocasi\u00e3o, foi divulgada a sua decis\u00e3o de tornar ineleg\u00edveis o atual governador do Maranh\u00e3o, Fl\u00e1vio Dino (PCdoB), Lu\u00eds Mendes Ferreira Filho e Domingos Alberto Alves de Sousa, respectivamente Prefeito e Vice-Prefeito do Munic\u00edpio de Coroat\u00e1 (MA), pelo per\u00edodo de oito anos subsequentes \u00e0 2016. A senten\u00e7a foi proferida sob os fundamentos de que, durante a campanha eleitoral para a chefia do poder executivo municipal daquele ano, houve abuso de poder pol\u00edtico.<\/em><\/p>\n<p><em>A magistrada vem sendo alvo de amea\u00e7as e acusa\u00e7\u00f5es que sugerem que ela teria assumido uma postura partid\u00e1ria, al\u00e9m de ter sua vida particular exposta publicamente pelos representados na a\u00e7\u00e3o legal e por seus aliados. Seus perseguidores se recusam a entender que as nobres decis\u00f5es judiciais s\u00e3o pautadas por fundamenta\u00e7\u00e3o jur\u00eddica e est\u00e3o adstritas aos mais diversos recursos judiciais.<\/em><\/p>\n<p><em>A ANAMAGES n\u00e3o admite que magistrados sejam alvos de amea\u00e7as e persegui\u00e7\u00f5es pol\u00edticas, sob quaisquer circunst\u00e2ncias, e proceder\u00e1 a imediata instaura\u00e7\u00e3o de procedimento para apurar tais fatos. A isen\u00e7\u00e3o no trabalho dos ju\u00edzes \u00e9 um dos pilares do Estado Democr\u00e1tico e preservar a liberdade da atua\u00e7\u00e3o jurisdicional \u00e9 um dos compromissos da Associa\u00e7\u00e3o. &#8220;Repudiamos as declara\u00e7\u00f5es levianas que amea\u00e7am o procedimento legal proferidas pelo chefe do executivo do Estado do Maranh\u00e3o e seus aliados contra a ju\u00edza Anelise Nogueira Reginato. Tais atos ferem a democracia e a honra da magistratura brasileira&#8221;, declarou o presidente Magid Nauef L\u00e1uar.<\/em><\/p>\n<p><em>Mesmo estarrecida, a ju\u00edza, que \u00e9 natural de Curitiba\/PR, afirma que n\u00e3o ir\u00e1 se curvar diante dos ataques e que ir\u00e1 perpetuar em sua miss\u00e3o, com dignidade, imparcialidade e coragem. &#8220;Decidi de acordo com as leis, com as provas e com a minha convic\u00e7\u00e3o. N\u00e3o tenho partido pol\u00edtico.&#8221; Anelise foi a \u00fanica mulher empossada na turma de 2010 do Tribunal de Justi\u00e7a do Maranh\u00e3o (TJMA). Como oradora, \u00e0 \u00e9poca, proferiu discurso emotivo: \u201cVestir a toga de juiz n\u00e3o \u00e9 o bastante. Estarei realizada se conseguir honrar essa toga\u201d, disse a paranaense.<\/em><\/p>\n<p><em>Por fim, A ANAMAGES, entidade vocacionada e reconhecida por defender, de forma intransigente, os direitos e prerrogativas dos Magistrados Estaduais, publicamente desagrava a Ju\u00edza Anelise e refor\u00e7a que tomar\u00e1 todas as medidas para garantir que a magistrada continue exercendo a sua fun\u00e7\u00e3o livre de amea\u00e7as e segura para exarar as decis\u00f5es sem medo e com justi\u00e7a.<\/em><\/p>\n<p style=\"text-align: center;\">Magid Nauef L\u00e1uar, juiz de Direito<\/p>\n<p style=\"text-align: center;\">Presidente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Nacional dos Magistrados Estaduais (Anamages) fez uma defesa incisiva da ju\u00edza Anelise Nogueira Reginato, atacada covardemente pelo grupo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-54154","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o &quot;levianas&quot; e &quot;ferem a democracia e a honra da magistratura brasileira&quot; - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o &quot;levianas&quot; e &quot;ferem a democracia e a honra da magistratura brasileira&quot; - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"A Associa\u00e7\u00e3o Nacional dos Magistrados Estaduais (Anamages) fez uma defesa incisiva da ju\u00edza Anelise Nogueira Reginato, atacada covardemente pelo grupo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-10T13:13:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/\",\"name\":\"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o \\\"levianas\\\" e \\\"ferem a democracia e a honra da magistratura brasileira\\\" - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg\",\"datePublished\":\"2018-08-10T13:13:20+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o &#8220;levianas&#8221; e &#8220;ferem a democracia e a honra da magistratura brasileira&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o \"levianas\" e \"ferem a democracia e a honra da magistratura brasileira\" - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/","og_locale":"pt_BR","og_type":"article","og_title":"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o \"levianas\" e \"ferem a democracia e a honra da magistratura brasileira\" - Daniel Matos","og_description":"A Associa\u00e7\u00e3o Nacional dos Magistrados Estaduais (Anamages) fez uma defesa incisiva da ju\u00edza Anelise Nogueira Reginato, atacada covardemente pelo grupo [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/","og_site_name":"Daniel Matos","article_published_time":"2018-08-10T13:13:20+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/","name":"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o \"levianas\" e \"ferem a democracia e a honra da magistratura brasileira\" - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg","datePublished":"2018-08-10T13:13:20+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2018\/08\/juiza-anelise.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/associacao-nacional-de-magistrados-estaduais-diz-que-declaracoes-de-flavio-dino-contra-decisao-de-juiza-sao-levianas-e-ferem-a-democracia-e-a-honra-da-magistratura-brasileira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Associa\u00e7\u00e3o Nacional de Magistrados Estaduais diz que declara\u00e7\u00f5es de Fl\u00e1vio Dino contra decis\u00e3o de ju\u00edza s\u00e3o &#8220;levianas&#8221; e &#8220;ferem a democracia e a honra da magistratura brasileira&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/54154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=54154"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/54154\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=54154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=54154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=54154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}