{"id":66350,"date":"2019-09-22T21:21:49","date_gmt":"2019-09-23T00:21:49","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=66350"},"modified":"2019-09-22T21:21:49","modified_gmt":"2019-09-23T00:21:49","slug":"prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/","title":{"rendered":"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil"},"content":{"rendered":"\n<p class=\"has-text-color has-large-font-size has-vivid-red-color\">Al\u00e9m da creche, foram entregues tamb\u00e9m pelo prefeito Edivaldo dois carros-biblioteca totalmente equipados e adaptados com obras infantis; a a\u00e7\u00e3o refor\u00e7a os investimentos que o prefeito vem realizado na \u00e1rea visando a melhoria da qualidade do ensino<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg\" alt=\"\" class=\"wp-image-66351\"\/><figcaption>Prefeito Edivaldo e primeira-dama, Camila Holanda, s\u00e3o cumprimentados pela comunidade na inaugura\u00e7\u00e3o da creche<\/figcaption><\/figure><\/div>\n\n\n\n<p>O prefeito Edivaldo Holanda Junior inaugurou neste s\u00e1bado (21) a U.E.B. Carlos Salom\u00e3o Chaib, localizada na Ch\u00e1cara Brasil. A creche municipal vai atender, em tempo integral, 190 crian\u00e7as de 2 a 5 anos de idade da regi\u00e3o. As matr\u00edculas j\u00e1 foram realizadas, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (Semed), e as aulas j\u00e1 come\u00e7am na ter\u00e7a-feira (24). A abertura de novas vagas para a educa\u00e7\u00e3o infantil integra a pol\u00edtica educacional que o prefeito Edivaldo implantou e vem desenvolvendo em sua gest\u00e3o. Al\u00e9m da creche, foram entregues tamb\u00e9m dois carros-biblioteca totalmente equipados e adaptados com obras infantis que promover\u00e3o a valoriza\u00e7\u00e3o da cultura maranhense e atender\u00e3o todas as escolas da rede municipal de ensino, seguindo um cronograma pr\u00f3prio.<\/p>\n\n\n\n<p>&#8220;Estamos fazendo a entrega desta creche hoje com a certeza de que ela trar\u00e1 muitos benef\u00edcios para as crian\u00e7as e fam\u00edlias da regi\u00e3o. A creche conta com toda a estrutura e equipe de profissionais necess\u00e1rias para atender todas as necessidades dos alunos. A equipe \u00e9 multiprofissional com nutricionistas, psic\u00f3logos, fonoaudi\u00f3logos e outros. Ainda este ano entregaremos creches na Cidade Oper\u00e1ria e Morada do Sol e temos outras em constru\u00e7\u00e3o&#8221;, disse o prefeito Edivaldo que estava acompanhado da primeira-dama, Camila Holanda, do vice-prefeito Julio Pinheiro e de secret\u00e1rios municipais, entre eles o titular da Semed, Moacir Feitosa.<\/p>\n\n\n\n<p>Tamb\u00e9m acompanharam o prefeito na inaugura\u00e7\u00e3o a promotora da Educa\u00e7\u00e3o, Maria Luciane Lisboa Belo, os vereadores Marquinhos e Paulo Vitor e o presidente do Sinduscon-MA, F\u00e1bio Nanuz, entre outras autoridades.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche2.jpg\" alt=\"\" class=\"wp-image-66352\"\/><figcaption>Prefeito Edivaldo, vice-prefeito, J\u00falio Pinheiro, secret\u00e1rios Moacir Feitosa (Educa\u00e7\u00e3o) e Nonato Chocolate (Representa\u00e7\u00e3o Parlamentar) com educadoras da creche<\/figcaption><\/figure><\/div>\n\n\n\n<p>A unidade atender\u00e1 principalmente a crian\u00e7as dos bairros da regi\u00e3o do Turu, como Divin\u00e9ia, Vila Luiz\u00e3o, Alonso Costa, Ch\u00e1cara Brasil, entre outros. Est\u00e3o sendo oferecidas 190 vagas em per\u00edodo integral, das 8h \u00e0s 17h. A nova creche \u00e9 totalmente climatizada e com toda infraestrutura para ofertar um servi\u00e7o de qualidade \u00e0s crian\u00e7as e suas fam\u00edlias. S\u00e3o espa\u00e7os idealizados para o acolhimento e desenvolvimentos das crian\u00e7as.<\/p>\n\n\n\n<p>O vice-prefeito de S\u00e3o Lu\u00eds, J\u00falio Pinheiro, destacou que a creche ser\u00e1 um instrumento transformador na regi\u00e3o. &#8220;Eu tamb\u00e9m sou professor, ent\u00e3o, sei muito bem a import\u00e2ncia que essa creche ter\u00e1 para essas fam\u00edlias. A melhoria da educa\u00e7\u00e3o tem sido um dos mais importantes compromissos do prefeito Edivaldo com S\u00e3o Lu\u00eds e muitos avan\u00e7os j\u00e1 foram conquistados&#8221;, informou.<\/p>\n\n\n\n<p><strong>APROVA\u00c7\u00c3O<\/strong><\/p>\n\n\n\n<p>As m\u00e3es presentes na solenidade de inaugura\u00e7\u00e3o, aprovaram a estrutura do espa\u00e7o e est\u00e3o ansiosas pelo in\u00edcio das aulas. Ana Carolina Pereira Costa, m\u00e3e dos g\u00eameos Samuel e Davi, de tr\u00eas anos, disse que agora ficar\u00e1 mais tranquila, tendo onde deixar os filhos. &#8220;Eu dava um agrado para minha prima ficar com eles enquanto eu trabalho, pois n\u00e3o tenho como pagar uma creche particular, principalmente porque s\u00e3o dois e ficaria muito caro. Agora vai ficar \u00f3timo. Eles j\u00e1 est\u00e3o matriculados. Eu visitei a creche e gostei muito das instala\u00e7\u00f5es&#8221;, disse.<\/p>\n\n\n\n<p>Marcilene da Silva Santos tem um filho de 3 anos que tamb\u00e9m estudar\u00e1 na creche. Ela \u00e9 representante da Comiss\u00e3o de Pais e agradeceu ao prefeito Edivaldo pela entrega da creche. &#8220;N\u00f3s tivemos v\u00e1rias reuni\u00f5es para que pud\u00e9ssemos contribuir com esse projeto. Acompanhamos de perto a constru\u00e7\u00e3o e digo que estou emocionada com toda a estrutura que nossos filhos v\u00e3o ter. Esta creche era muito aguardada e vai mudar a vida das fam\u00edlias da regi\u00e3o&#8221;, afirmou.<\/p>\n\n\n\n<p><strong>ESTRUTURA<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche3.jpg\" alt=\"\" class=\"wp-image-66353\"\/><figcaption>Uma das 10 salas de aula que receber\u00e3o as crian\u00e7as e educadores da creche<\/figcaption><\/figure><\/div>\n\n\n\n<p>A creche conta com 10 salas de aula, sala de multiuso, com TV e jogos educativos, frald\u00e1rio, cozinha, p\u00e1tio coberto, sala para amamenta\u00e7\u00e3o, \u00e1rea livre com parquinho e jardim; secretaria, sala de professores e dire\u00e7\u00e3o, al\u00e9m de seis banheiros, sendo tr\u00eas masculinos e tr\u00eas femininos. A sala de multiuso servir\u00e1 tamb\u00e9m para reuni\u00f5es e treinamento dos professores e educadores. A unidade fornecer\u00e1 todas as refei\u00e7\u00f5es \u00e0s crian\u00e7as &#8211; do caf\u00e9 da manh\u00e3 ao jantar &#8211; antes de retornarem para casa.<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio municipal de Educa\u00e7\u00e3o, Moacir Feitosa, o per\u00edodo integral de atendimento \u00e9 um diferencial deste equipamento. &#8220;A creche tem uma excelente estrutura para proporcionar uma educa\u00e7\u00e3o de qualidade e dar aos pais a tranquilidade que necessitam, al\u00e9m de oferecer o atendimento em tempo integral e para os profissionais altamente capacitados para atuarem com meninos e meninas de 2 a 5 anos&#8221;, pontuou.<\/p>\n\n\n\n<p>As aulas come\u00e7am na ter\u00e7a-feira (24). As matr\u00edculas foram realizadas do dia 9 ao dia 12 deste m\u00eas, e no dia 13 foi realizada uma reuni\u00e3o com os pais das crian\u00e7as que ser\u00e3o atendidas. Durante a reuni\u00e3o, foram dadas explica\u00e7\u00f5es sobre como ser\u00e1 o funcionamento da creche, desde a parte pedag\u00f3gica, rotina, alimenta\u00e7\u00e3o, hor\u00e1rios, at\u00e9 as especificidades de cada idade. A reuni\u00e3o aconteceu em dois momentos: um com os pais de crian\u00e7as de 2 e 3 anos e outro com os das crian\u00e7as de 4 e 5 anos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche4.jpg\" alt=\"\" class=\"wp-image-66354\"\/><figcaption>Sala de recrea\u00e7\u00e3o climatizada conta com v\u00e1rios brinquedos para as crian\u00e7as<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>CARROS-BIBLIOTECA<\/strong><\/p>\n\n\n\n<p>Durante a entrega da creche, o prefeito Edivaldo entregou dois carros-biblioteca completamente equipados. S\u00e3o duas vans totalmente adaptadas para funcionar como bibliotecas m\u00f3veis e para receber meninos e meninas, estimulando o interesse pela leitura e desenvolvendo o prazer de ler. Um dos ve\u00edculos, que ser\u00e1 destinado \u00e0 Educa\u00e7\u00e3o Infantil, possui o tema &#8220;Lendas Maranhenses&#8221;, e ilustra nossas principais lendas: Serpente Encantada, A carruagem de Ana Jansen, Rei Dom Sebasti\u00e3o, entre outras. O acervo tamb\u00e9m evidencia a produ\u00e7\u00e3o liter\u00e1ria maranhense com obras de autores como Marta Reis, Wilson Marques, Marcio Henrique, Sharlene Serra e Natinho Costa.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche5.jpg\" alt=\"\" class=\"wp-image-66355\"\/><figcaption>Prefeito Edivaldo Holanda J\u00fanior com grupo de crian\u00e7as e educadora em carro biblioteca<\/figcaption><\/figure><\/div>\n\n\n\n<p>O outro carro, que beneficiar\u00e1 estudantes do Ensino Fundamental, traz dois cen\u00e1rios: um sobre a \u00e1rea urbana, com imagens do Centro Hist\u00f3rico de S\u00e3o Lu\u00eds e da \u00e1rea rural, valorizando a natureza. Os dois cen\u00e1rios fazem alus\u00e3o \u00e0s brincadeiras e jogos que ser\u00e3o realizados nas atividades do carro biblioteca. Neste carro h\u00e1 um acervo de mais de 200 livros com textos cl\u00e1ssicos da literatura infanto-juvenil entre eles Os Tr\u00eas Porquinhos, Branca de Neve, Pin\u00f3quio, Chapeuzinho Vermelho, entre outros.<\/p>\n\n\n\n<p><strong>FORMA\u00c7\u00c3O<\/strong><\/p>\n\n\n\n<p>Os profissionais que ir\u00e3o trabalhar na U.E.B Carlos Salom\u00e3o Chaib est\u00e3o h\u00e1 um m\u00eas participando de forma\u00e7\u00e3o, em diversas tem\u00e1ticas, com o objetivo de capacit\u00e1-los para receberem as crian\u00e7as. Dentre as tem\u00e1ticas que foram tratadas durante forma\u00e7\u00e3o est\u00e3o os &#8216;Direitos das Crian\u00e7as&#8217;, &#8216;Autismo&#8217;, &#8216;Primeiros Socorros&#8217;, &#8216;O Papel do Cuidador na Escola&#8217;, a &#8216;Base Nacional Comum Curricular (BNCC) para a Educa\u00e7\u00e3o Infantil&#8217;, entre outros.<\/p>\n\n\n\n<p><strong>AVAN\u00c7OS NA EDUCA\u00c7\u00c3O<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche6.jpg\" alt=\"\" class=\"wp-image-66356\"\/><figcaption>Fachada da UEB Salom\u00e3o Chaib e creche e pr\u00e9-escola. na Ch\u00e1cara Brasil  <\/figcaption><\/figure><\/div>\n\n\n\n<p>A educa\u00e7\u00e3o \u00e9 mais uma \u00e1rea em que o prefeito Edivaldo vem consolidando avan\u00e7os ao longo da sua gest\u00e3o. Para reestruturar a educa\u00e7\u00e3o municipal, o prefeito Edivaldo implantou o macroprograma Educar Mais estruturado em cinco eixos: reforma da rede f\u00edsica, avalia\u00e7\u00e3o escolar, gest\u00e3o escolar, forma\u00e7\u00e3o docente e monitoramento permanente.<\/p>\n\n\n\n<p>Atrav\u00e9s do Programa, j\u00e1 foram reformadas mais de 170 escolas municipais e o sistema de ensino da rede municipal conta atualmente com mais de mil salas de aula com ar-condicionado, garantindo mais conforto para os estudantes e profissionais.<\/p>\n\n\n\n<p>A Prefeitura de S\u00e3o Lu\u00eds j\u00e1 tem mais duas creches com obras em finaliza\u00e7\u00e3o. Est\u00e3o sendo conclu\u00eddas tamb\u00e9m outras na Cidade Oper\u00e1ria e Morada do Sol.<\/p>\n\n\n\n<p><strong>Fonte:<\/strong> Secretaria Municipal de Comunica\u00e7\u00e3o (Secom)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00e9m da creche, foram entregues tamb\u00e9m pelo prefeito Edivaldo dois carros-biblioteca totalmente equipados e adaptados com obras infantis; a a\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-66350","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"Al\u00e9m da creche, foram entregues tamb\u00e9m pelo prefeito Edivaldo dois carros-biblioteca totalmente equipados e adaptados com obras infantis; a a\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-23T00:21:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/\",\"name\":\"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg\",\"datePublished\":\"2019-09-23T00:21:49+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil - Daniel Matos","og_description":"Al\u00e9m da creche, foram entregues tamb\u00e9m pelo prefeito Edivaldo dois carros-biblioteca totalmente equipados e adaptados com obras infantis; a a\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/","og_site_name":"Daniel Matos","article_published_time":"2019-09-23T00:21:49+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/","name":"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg","datePublished":"2019-09-23T00:21:49+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2019\/09\/creche.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/prefeito-edivaldo-entrega-creche-em-tempo-integral-na-chacara-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Prefeito Edivaldo entrega creche em tempo integral na Ch\u00e1cara Brasil"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/66350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=66350"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/66350\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=66350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=66350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=66350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}