{"id":8804,"date":"2013-02-01T15:15:05","date_gmt":"2013-02-01T18:15:05","guid":{"rendered":"https:\/\/www.blogsoestado.com\/danielmatos\/?p=8804"},"modified":"2013-02-01T15:15:05","modified_gmt":"2013-02-01T18:15:05","slug":"empossada-nova-mesa-diretora-da-al","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/","title":{"rendered":"Empossada nova Mesa Diretora da AL"},"content":{"rendered":"<figure id=\"attachment_8805\" aria-describedby=\"caption-attachment-8805\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.blogsoestado.com\/danielmatos\/2013\/02\/01\/empossada-nova-mesa-diretora-da-al\/mesa-diretora\/\" rel=\"attachment wp-att-8805\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-8805\" alt=\"Presidida por Arnaldo Melo, Mesa Diretora da Assembleia dever\u00e1 contar tamb\u00e9m com Max Barros como 1\u00ba vice\" src=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg\" width=\"640\" height=\"426\" \/><\/a><figcaption id=\"caption-attachment-8805\" class=\"wp-caption-text\">Presidida por Arnaldo Melo, Mesa Diretora da Assembleia dever\u00e1 contar tamb\u00e9m com Max Barros como 1\u00ba vice<\/figcaption><\/figure>\n<p>Uma sess\u00e3o solene, realizada no Sal\u00e3o Nobre Deputado Gen\u00e9sio Rego, marcou, na manh\u00e3 desta sexta-feira (1\u00ba), a posse dos membros da nova Mesa Diretora da Assembleia Legislativa. O presidente da Casa, deputado Arnaldo Melo (PMDB), declarou empossada a nova Mesa, ap\u00f3s o comunicado de que ficara vago o cargo de primeiro vice-presidente.<\/p>\n<p>O deputado Ricardo Murad (PMDB), que seria investido no posto de primeiro vice-presidente, comunicou ter declinado do cargo, para permanecer como deputado licenciado, exercendo o comando da Secretaria de Estado da Sa\u00fade.<\/p>\n<p>Em conson\u00e2ncia com o Regimento Interno da Casa, Arnaldo Melo declarou que ser\u00e1 aberto o prazo regimental para a elei\u00e7\u00e3o do novo primeiro vice-presidente. E informou que, na manh\u00e3 da pr\u00f3xima segunda-feira (dia 4), ser\u00e1 realizada a sess\u00e3o solene de reabertura dos trabalhos da Casa.<\/p>\n<p>Al\u00e9m de Arnaldo Melo, reconduzido ao cargo de presidente, assinaram o ato de posse os deputados Eduardo Braide (segundo vice-presidente), Marcelo Tavares (terceiro vice-presidente), Gard\u00eania Castelo (quarto vice-presidente), Rog\u00e9rio Cafeteira (primeiro secret\u00e1rio), Carlinhos Flor\u00eancio (segundo secret\u00e1rio), Dr. P\u00e1dua (terceiro secret\u00e1rio) e Z\u00e9 Carlos (quarto secret\u00e1rio).<\/p>\n<p><strong>Compromisso reiterado<\/strong><\/p>\n<p>Em seu discurso, Arnaldo Melo foi enf\u00e1tico ao afirmar que a nova Mesa Diretora \u2013 eleita no dia 12 de julho de 2012, para o segundo bi\u00eanio da atual legislatura, que compreende o per\u00edodo de 1\u00ba de fevereiro de 2013 a 31 de janeiro de 2015 &#8211; tem o desafio de manter o trabalho pela moderniza\u00e7\u00e3o da Casa, para que o Parlamento maranhense fique cada vez mais pr\u00f3ximo de cada cidad\u00e3o.<\/p>\n<p>\u201cReitero, nesta solenidade, o compromisso assumido na gest\u00e3o passada de trabalhar para modernizar esta Casa, na parte tecnol\u00f3gica, para que a sociedade tenha cada vez mais condi\u00e7\u00f5es de poder acompanhar o trabalho de cada deputado\u201d, afirmou Arnaldo Melo.<\/p>\n<p>Al\u00e9m de agradecer o apoio de todos os diretores da Casa e dos profissionais da imprensa, que \u201cd\u00e3o uma grande contribui\u00e7\u00e3o divulgando de forma positiva os nossos trabalhos\u201d, Arnaldo Melo fez quest\u00e3o de fazer uma defer\u00eancia especial ao trabalho realizado pelos membros da Mesa Diretora anterior: deputados Marcos Caldas, Francisca Primo, Neto Evangelista, Jota Pinto, Edil\u00e1zio J\u00fanior, Afonso Manoel, Cleide Coutinho e H\u00e9lio Soares.<\/p>\n<p>Conclamando \u00e0 manuten\u00e7\u00e3o da unidade, Arnaldo Melo lembrou que, de forma honrosa, o Plen\u00e1rio conta com a presen\u00e7a de tr\u00eas ex-presidentes da Casa: Manoel Ribeiro, Carlos Alberto Milhomem e Marcelo Tavares. \u201cJuntos somos fortes. A uni\u00e3o \u00e9 o \u00fanico caminho para o fortalecimento deste Poder\u201d, declarou Arnaldo Melo.<\/p>\n<p>A cerim\u00f4nia, encerrada com a participa\u00e7\u00e3o de m\u00fasicos do Quarteto de Cordas Kadenza, contou tamb\u00e9m com a presen\u00e7a do presidente do Tribunal de Contas do Estado (TCE), conselheiro Edmar Cutrim; do presidente da C\u00e2mara Municipal de S\u00e3o Lu\u00eds, vereador Ant\u00f4nio Isaias Pereirinha; e do secret\u00e1rio de Estado de Articula\u00e7\u00e3o Pol\u00edtica e Cidades, Hildo Rocha, que na solenidade representou a governadora Roseana Sarney.<\/p>\n<p><strong>Fonte:<\/strong> Ag\u00eancia Assembleia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma sess\u00e3o solene, realizada no Sal\u00e3o Nobre Deputado Gen\u00e9sio Rego, marcou, na manh\u00e3 desta sexta-feira (1\u00ba), a posse dos membros [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8804","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Empossada nova Mesa Diretora da AL - Daniel Matos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empossada nova Mesa Diretora da AL - Daniel Matos\" \/>\n<meta property=\"og:description\" content=\"Uma sess\u00e3o solene, realizada no Sal\u00e3o Nobre Deputado Gen\u00e9sio Rego, marcou, na manh\u00e3 desta sexta-feira (1\u00ba), a posse dos membros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniel Matos\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-01T18:15:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/\",\"name\":\"Empossada nova Mesa Diretora da AL - Daniel Matos\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg\",\"datePublished\":\"2013-02-01T18:15:05+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empossada nova Mesa Diretora da AL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/danielmatos\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/danielmatos\/\",\"name\":\"Daniel Matos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empossada nova Mesa Diretora da AL - Daniel Matos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/","og_locale":"pt_BR","og_type":"article","og_title":"Empossada nova Mesa Diretora da AL - Daniel Matos","og_description":"Uma sess\u00e3o solene, realizada no Sal\u00e3o Nobre Deputado Gen\u00e9sio Rego, marcou, na manh\u00e3 desta sexta-feira (1\u00ba), a posse dos membros [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/","og_site_name":"Daniel Matos","article_published_time":"2013-02-01T18:15:05+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/","url":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/","name":"Empossada nova Mesa Diretora da AL - Daniel Matos","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg","datePublished":"2013-02-01T18:15:05+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg","contentUrl":"https:\/\/www.blogsoestado.com\/danielmatos\/files\/2013\/02\/mesa-diretora.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/empossada-nova-mesa-diretora-da-al\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/danielmatos\/"},{"@type":"ListItem","position":2,"name":"Empossada nova Mesa Diretora da AL"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/danielmatos\/#website","url":"https:\/\/www.blogsoestado.com\/danielmatos\/","name":"Daniel Matos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/danielmatos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/8804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/comments?post=8804"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/posts\/8804\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/media?parent=8804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/categories?post=8804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/danielmatos\/wp-json\/wp\/v2\/tags?post=8804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}