{"id":16565,"date":"2025-08-16T10:32:50","date_gmt":"2025-08-16T13:32:50","guid":{"rendered":"https:\/\/www.blogsoestado.com\/evandrojunior\/?p=16565"},"modified":"2025-08-16T10:35:38","modified_gmt":"2025-08-16T13:35:38","slug":"maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/","title":{"rendered":"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-576x1024.jpeg\" alt=\"\" class=\"wp-image-16569\" srcset=\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-576x1024.jpeg 576w, https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-169x300.jpeg 169w, https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1.jpeg 720w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><figcaption class=\"wp-element-caption\"><strong>Shaullo Freire e Thiago Pimenta, da Maison Eventos &amp; Buffet, participam da ABCasa Fair<\/strong><\/figcaption><\/figure>\n\n\n\n<p><strong>S\u00c3O LU\u00cdS <\/strong>&#8211; O Maranh\u00e3o marca presen\u00e7a na ABCasa Fair, maior feira de casa e decora\u00e7\u00e3o do Brasil. Os s\u00f3cios-propriet\u00e1rios da Maison Eventos &amp; Buffet (@maisoneventos), Shaullo Freire e Thiago Pimenta, participam do evento, em andamento na Expo Center Norte, em S\u00e3o Paulo, e que re\u00fane, em um s\u00f3 lugar, artigos para casa, decora\u00e7\u00e3o, presentes, utilidades dom\u00e9sticas, festas, entre diversos outros.<\/p>\n\n\n\n<p>S\u00e3o mais de 350 expositores espalhados no pavilh\u00e3o.\u00a0Afinal, \u00e9 uma das maiores feiras Business-to-Business da Am\u00e9rica Latina. Profissionais de todo o Brasil e do exterior est\u00e3o participando dessa feira, que envolve os mais diversos segmentos, entre restaurantes, buffets, lojas de presentes, hot\u00e9is, lojas de\u00a0casa e decora\u00e7\u00e3o, confeitarias, lojas de flores, de presentes criativos, de cama, mesa e banho e por a\u00ed vai. Entre os profissionais est\u00e3o designers de interiores, decoradores, arquitetos, personal organizers e influenciadores do setor.<\/p>\n\n\n\n<p>A Maison Eventos &amp; Buffet, por interm\u00e9dio de seus representantes, aproveita o evento para network e troca de experi\u00eancias, buscando as novas tend\u00eancias do setor. \u00c9 que a Maison tem uma trajet\u00f3ria marcada por inova\u00e7\u00e3o e compromisso com a qualidade. Da\u00ed a busca por novidades sempre. \u00c9 uma empresa com sede em S\u00e3o Lu\u00eds refer\u00eancia na realiza\u00e7\u00e3o de eventos que unem sabor, est\u00e9tica e emo\u00e7\u00e3o. N\u00e3o \u00e9 \u00e0 toa que j\u00e1 assinou produ\u00e7\u00f5es memor\u00e1veis em casamentos, anivers\u00e1rios, formaturas, eventos corporativos e celebra\u00e7\u00f5es exclusivas, sempre com um toque de requinte e criatividade, sua marca registrada.<\/p>\n\n\n\n<p><strong>Atualiza\u00e7\u00e3o, inspira\u00e7\u00e3o e conex\u00e3o<\/strong><\/p>\n\n\n\n<p>&#8220;Participar da maior feira de decora\u00e7\u00e3o e lou\u00e7arias da Am\u00e9rica Latina \u00e9 muito mais do que um evento, mas uma oportunidade \u00fanica de atualiza\u00e7\u00e3o, inspira\u00e7\u00e3o e conex\u00e3o com as principais tend\u00eancias do mercado. Estar presente significa ter acesso em primeira m\u00e3o \u00e0s novidades, lan\u00e7amentos e inova\u00e7\u00f5es que v\u00e3o ditar o rumo das nossas mesas e apresenta\u00e7\u00e3o nos pr\u00f3ximos dez meses&#8221;, diz Shaullo Freire.<\/p>\n\n\n\n<p>&#8220;Essa experi\u00eancia \u00e9 fundamental. Atualizar-me constantemente garante que possamos oferecer ao nosso cliente o que h\u00e1 de mais atual, criativo e funcional, trazendo solu\u00e7\u00f5es que unem est\u00e9tica, qualidade e personalidade. Cada detalhe aprendido, cada contato estabelecido e cada refer\u00eancia absorvida contribuem para que entreguemos projetos cada vez mais completos, sofisticados e alinhados \u00e0s expectativas e sonhos de quem confia no nosso trabalho&#8221;, complementa Thiago Pimenta.<\/p>\n\n\n\n<p>Com uma d\u00e9cada de hist\u00f3ria e um futuro promissor pela frente, a Maison segue inspirando o mercado e elevando o padr\u00e3o da gastronomia de eventos na cidade. Os servi\u00e7os incluem sobremesas e esta\u00e7\u00f5es de doces que encantam os convidados; buffet personalizado com card\u00e1pios adaptados ao estilo de cada evento; ilhas gastron\u00f4micas tem\u00e1ticas e variadas; coquet\u00e9is volantes e esta\u00e7\u00f5es interativas e card\u00e1pios exclusivos para jantares e almo\u00e7os especiais. O contato \u00e9 (98) 98462-8920. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00c3O LU\u00cdS &#8211; O Maranh\u00e3o marca presen\u00e7a na ABCasa Fair, maior feira de casa e decora\u00e7\u00e3o do Brasil. Os s\u00f3cios-propriet\u00e1rios [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16565","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina - Evandro Junior<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina - Evandro Junior\" \/>\n<meta property=\"og:description\" content=\"S\u00c3O LU\u00cdS &#8211; O Maranh\u00e3o marca presen\u00e7a na ABCasa Fair, maior feira de casa e decora\u00e7\u00e3o do Brasil. Os s\u00f3cios-propriet\u00e1rios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/\" \/>\n<meta property=\"og:site_name\" content=\"Evandro Junior\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-16T13:32:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-16T13:35:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-576x1024.jpeg\" \/>\n<meta name=\"author\" content=\"Evandro Junior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evandro Junior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/\",\"name\":\"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina - Evandro Junior\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-576x1024.jpeg\",\"datePublished\":\"2025-08-16T13:32:50+00:00\",\"dateModified\":\"2025-08-16T13:35:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1.jpeg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1.jpeg\",\"width\":720,\"height\":1280,\"caption\":\"Shaullo Freire e Thiago Pimenta, da Maison Eventos &amp; Buffet, participam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/\",\"name\":\"Evandro Junior\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be\",\"name\":\"Evandro Junior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g\",\"caption\":\"Evandro Junior\"},\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/author\/evandrojunior\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina - Evandro Junior","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/","og_locale":"pt_BR","og_type":"article","og_title":"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina - Evandro Junior","og_description":"S\u00c3O LU\u00cdS &#8211; O Maranh\u00e3o marca presen\u00e7a na ABCasa Fair, maior feira de casa e decora\u00e7\u00e3o do Brasil. Os s\u00f3cios-propriet\u00e1rios [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/","og_site_name":"Evandro Junior","article_published_time":"2025-08-16T13:32:50+00:00","article_modified_time":"2025-08-16T13:35:38+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-576x1024.jpeg","type":"","width":"","height":""}],"author":"Evandro Junior","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Evandro Junior","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/","name":"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina - Evandro Junior","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1-576x1024.jpeg","datePublished":"2025-08-16T13:32:50+00:00","dateModified":"2025-08-16T13:35:38+00:00","author":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be"},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1.jpeg","contentUrl":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2025\/08\/WhatsApp-Image-2025-08-16-at-09.47.35-1.jpeg","width":720,"height":1280,"caption":"Shaullo Freire e Thiago Pimenta, da Maison Eventos &amp; Buffet, participam"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2025\/08\/16\/maison-eventos-buffet-participa-da-maior-feira-de-casa-e-decoracao-da-america-latina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/evandrojunior\/"},{"@type":"ListItem","position":2,"name":"Maison Eventos &amp; Buffet participa da maior feira de casa e decora\u00e7\u00e3o da Am\u00e9rica Latina"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#website","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/","name":"Evandro Junior","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/evandrojunior\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be","name":"Evandro Junior","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g","caption":"Evandro Junior"},"url":"https:\/\/www.blogsoestado.com\/evandrojunior\/author\/evandrojunior\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/16565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/comments?post=16565"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/16565\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/media?parent=16565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/categories?post=16565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/tags?post=16565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}