{"id":18510,"date":"2026-05-11T11:53:26","date_gmt":"2026-05-11T14:53:26","guid":{"rendered":"https:\/\/www.blogsoestado.com\/evandrojunior\/?p=18510"},"modified":"2026-05-11T16:03:45","modified_gmt":"2026-05-11T19:03:45","slug":"cristiano-sardinha-o-animal-social","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/","title":{"rendered":"Cristiano Sardinha: &#8220;O animal social&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16-1024x684.jpeg\" alt=\"\" class=\"wp-image-18511\" srcset=\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16-1024x684.jpeg 1024w, https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16-300x200.jpeg 300w, https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16-768x513.jpeg 768w, https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><br><strong>No palco da natureza, a esp\u00e9cie humana est\u00e1 bem longe de ser a mais forte fisicamente<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Estudos gen\u00e9ticos comprovam que h\u00e1 menos de 1% de diferen\u00e7a entre as letras do DNA de um ser humano e um chimpanz\u00e9. Nessa linha, quando se analisa apenas a esp\u00e9cie humana, as distin\u00e7\u00f5es que possam existir entre as letras de DNA de pessoas diferentes, constata-se cientificamente que \u00e9 menos de 0,1%.<\/p>\n\n\n\n<p>Dessa forma, quaisquer condutas preconceituosas, racistas ou xenof\u00f3bicas, al\u00e9m de contrariarem a legalidade e a moralidade comum, s\u00e3o tamb\u00e9m profundamente ignorantes \u00e0 luz dos estudos gen\u00e9ticos e biol\u00f3gicos atuais.<\/p>\n\n\n\n<p>No palco da natureza, a esp\u00e9cie humana est\u00e1 bem longe de ser a mais forte fisicamente, mas o nosso c\u00e9rebro nos salvou, possibilitando que o instinto e a raz\u00e3o trabalhassem em parceria para fazermos perguntas e an\u00e1lises do nosso ambiente, em prol da sobreviv\u00eancia.<\/p>\n\n\n\n<p>Outra caracter\u00edstica que nos possibilitou sobreviver e evoluir, foi a nossa capacidade de nos associarmos, primeiramente em bandos, e depois em comunidades. Conforme Arist\u00f3teles observou, \u201cO homem \u00e9 um animal pol\u00edtico\u201d.<\/p>\n\n\n\n<p>&#8220;<em>O homem \u00e9 um animal pol\u00edtico ou naturalmente pol\u00edtico porque \u00e9 um ser carente e imperfeito que necessita de coisas (para desejar) e de outros (para se reunir), buscando a comunidade como o lugar em que, com os seus semelhantes, alcance a completude. Se fosse sem car\u00eancias, seria um deus e n\u00e3o precisaria da vida comunit\u00e1ria; se fosse uma besta selvagem nem sequer sentiria a falta de outros. Por n\u00e3o ser um deus nem uma besta feroz, o homem \u00e9 um animal pol\u00edtico (CHAU\u00cd, 2002, p.464)&#8221;.<\/em><\/p>\n\n\n\n<p>Estarmos hoje nos questionando sobre a causa do Universo, sermos conscientes de n\u00f3s mesmos, termos criado as variadas formas de arte, religi\u00e3o, filosofia, ci\u00eancia, leis, pol\u00edtica e sociedades s\u00e3o provas da beleza da sele\u00e7\u00e3o natural e da arquitetura da vida que apontam para uma intelig\u00eancia divina.<\/p>\n\n\n\n<p>Nascemos demasiadamente fr\u00e1geis e precisamos durante muito tempo dos outros para termos chances de sobreviv\u00eancia. Desde a inf\u00e2ncia, passando pela juventude, idade adulta e velhice, estabelecemos la\u00e7os de depend\u00eancia f\u00edsica e emocional com os nossos semelhantes.<\/p>\n\n\n\n<p>Mesmo ap\u00f3s a morte, restar\u00e1 a necessidade de algu\u00e9m, para que o nosso corpo receba um tratamento digno e para que o legado deixado possa prosseguir. Quer se goste ou n\u00e3o, a vida humana somente atinge a sua m\u00e1xima potencialidade, com o aux\u00edlio dos outros.<\/p>\n\n\n\n<p>A natureza revela que os seres vivos est\u00e3o todos interconectados de alguma maneira, havendo especial rela\u00e7\u00e3o de interdepend\u00eancia em diversas esp\u00e9cies de animais sociais, tais como o <em>homo sapiens<\/em>. Ao cuidarmos uns dos outros, zelamos por n\u00f3s mesmos, pelos nossos entes queridos e colaboramos para a preserva\u00e7\u00e3o da esp\u00e9cie humana.<\/p>\n\n\n\n<p><em><strong>Texto contigo no livro \u201cDEUS \u00c0 LUZ DA RAZ\u00c3O HUMANA\u201d, de Cristiano Sardinha, publicado pela Editora Novo S\u00e9culo. <\/strong><\/em><\/p>\n\n\n\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n\n\n\n<p><strong>Cristiano Sardinha \u00e9 escritor, professor e tabeli\u00e3o<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudos gen\u00e9ticos comprovam que h\u00e1 menos de 1% de diferen\u00e7a entre as letras do DNA de um ser humano e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18510","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cristiano Sardinha: &quot;O animal social&quot; - Evandro Junior<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristiano Sardinha: &quot;O animal social&quot; - Evandro Junior\" \/>\n<meta property=\"og:description\" content=\"Estudos gen\u00e9ticos comprovam que h\u00e1 menos de 1% de diferen\u00e7a entre as letras do DNA de um ser humano e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Evandro Junior\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T14:53:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T19:03:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Evandro Junior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evandro Junior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/\",\"name\":\"Cristiano Sardinha: \\\"O animal social\\\" - Evandro Junior\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16-1024x684.jpeg\",\"datePublished\":\"2026-05-11T14:53:26+00:00\",\"dateModified\":\"2026-05-11T19:03:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg\",\"width\":1200,\"height\":801,\"caption\":\"No palco da natureza, a esp\u00e9cie humana est\u00e1 bem longe de ser a mais forte fisicamente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristiano Sardinha: &#8220;O animal social&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/\",\"name\":\"Evandro Junior\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be\",\"name\":\"Evandro Junior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g\",\"caption\":\"Evandro Junior\"},\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/author\/evandrojunior\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristiano Sardinha: \"O animal social\" - Evandro Junior","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/","og_locale":"pt_BR","og_type":"article","og_title":"Cristiano Sardinha: \"O animal social\" - Evandro Junior","og_description":"Estudos gen\u00e9ticos comprovam que h\u00e1 menos de 1% de diferen\u00e7a entre as letras do DNA de um ser humano e [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/","og_site_name":"Evandro Junior","article_published_time":"2026-05-11T14:53:26+00:00","article_modified_time":"2026-05-11T19:03:45+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg","type":"image\/jpeg"}],"author":"Evandro Junior","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Evandro Junior","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/","name":"Cristiano Sardinha: \"O animal social\" - Evandro Junior","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16-1024x684.jpeg","datePublished":"2026-05-11T14:53:26+00:00","dateModified":"2026-05-11T19:03:45+00:00","author":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be"},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg","contentUrl":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-11.54.16.jpeg","width":1200,"height":801,"caption":"No palco da natureza, a esp\u00e9cie humana est\u00e1 bem longe de ser a mais forte fisicamente"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2026\/05\/11\/cristiano-sardinha-o-animal-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/evandrojunior\/"},{"@type":"ListItem","position":2,"name":"Cristiano Sardinha: &#8220;O animal social&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#website","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/","name":"Evandro Junior","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/evandrojunior\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be","name":"Evandro Junior","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g","caption":"Evandro Junior"},"url":"https:\/\/www.blogsoestado.com\/evandrojunior\/author\/evandrojunior\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/18510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/comments?post=18510"}],"version-history":[{"count":3,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/18510\/revisions"}],"predecessor-version":[{"id":18515,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/18510\/revisions\/18515"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/media?parent=18510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/categories?post=18510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/tags?post=18510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}