{"id":8155,"date":"2022-12-15T17:27:16","date_gmt":"2022-12-15T20:27:16","guid":{"rendered":"https:\/\/www.blogsoestado.com\/evandrojunior\/?p=8155"},"modified":"2022-12-15T17:27:16","modified_gmt":"2022-12-15T20:27:16","slug":"mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/","title":{"rendered":"&#8216;Mocosamba&#8217; acontece neste domingo em clima de final da Copa do Mundo"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg\" alt=\"\" class=\"wp-image-8156\" width=\"490\" height=\"588\"\/><\/figure><\/div>\n\n\n\n<p>S\u00e3o Lu\u00eds &#8211; Neste domingo (18) tem &#8216;Mocosamba&#8217;, a partir das 11h, no espa\u00e7o O Covil &#8211; Parrilha &amp; Cerveja, na Avenida Duque Bacelar, no Altos do Calhau, em clima de final da Copa do Mundo. <\/p>\n\n\n\n<p>O evento come\u00e7a \u00e0s 14h30 ao som do grupo Madrilenus, da Madre Deus, que levar\u00e1 repert\u00f3rio com o melhor do samba. O sambista Serrinha far\u00e1 uma participa\u00e7\u00e3o especial durante a programa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O card\u00e1pio ser\u00e1 assinado pelos Cheffs Osiel e Daniel &#8216;Santo Braseiro&#8217;. O p\u00fablico ser\u00e1 recebido pelo mestre Sinval, propriet\u00e1rio da casa. Destaque para os cortes de carnes especiais preparados na parrinha argentina e os deliciosos burgers.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Lu\u00eds &#8211; Neste domingo (18) tem &#8216;Mocosamba&#8217;, a partir das 11h, no espa\u00e7o O Covil &#8211; Parrilha &amp; Cerveja, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8155","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&#039;Mocosamba&#039; acontece neste domingo em clima de final da Copa do Mundo - Evandro Junior<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Mocosamba&#039; acontece neste domingo em clima de final da Copa do Mundo - Evandro Junior\" \/>\n<meta property=\"og:description\" content=\"S\u00e3o Lu\u00eds &#8211; Neste domingo (18) tem &#8216;Mocosamba&#8217;, a partir das 11h, no espa\u00e7o O Covil &#8211; Parrilha &amp; Cerveja, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Evandro Junior\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T20:27:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg\" \/>\n<meta name=\"author\" content=\"Evandro Junior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evandro Junior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/\",\"name\":\"'Mocosamba' acontece neste domingo em clima de final da Copa do Mundo - Evandro Junior\",\"isPartOf\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg\",\"datePublished\":\"2022-12-15T20:27:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#primaryimage\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg\",\"contentUrl\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Mocosamba&#8217; acontece neste domingo em clima de final da Copa do Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#website\",\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/\",\"name\":\"Evandro Junior\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be\",\"name\":\"Evandro Junior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g\",\"caption\":\"Evandro Junior\"},\"url\":\"https:\/\/www.blogsoestado.com\/evandrojunior\/author\/evandrojunior\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Mocosamba' acontece neste domingo em clima de final da Copa do Mundo - Evandro Junior","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/","og_locale":"pt_BR","og_type":"article","og_title":"'Mocosamba' acontece neste domingo em clima de final da Copa do Mundo - Evandro Junior","og_description":"S\u00e3o Lu\u00eds &#8211; Neste domingo (18) tem &#8216;Mocosamba&#8217;, a partir das 11h, no espa\u00e7o O Covil &#8211; Parrilha &amp; Cerveja, [&hellip;]","og_url":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/","og_site_name":"Evandro Junior","article_published_time":"2022-12-15T20:27:16+00:00","og_image":[{"url":"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg","type":"","width":"","height":""}],"author":"Evandro Junior","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Evandro Junior","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/","name":"'Mocosamba' acontece neste domingo em clima de final da Copa do Mundo - Evandro Junior","isPartOf":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#primaryimage"},"image":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg","datePublished":"2022-12-15T20:27:16+00:00","author":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be"},"breadcrumb":{"@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#primaryimage","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg","contentUrl":"https:\/\/www.blogsoestado.com\/evandrojunior\/files\/2022\/12\/WhatsApp-Image-2022-12-15-at-10.17.17-853x1024.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/2022\/12\/15\/mocosamba-acontece-neste-domingo-em-clima-de-final-da-copa-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.blogsoestado.com\/evandrojunior\/"},{"@type":"ListItem","position":2,"name":"&#8216;Mocosamba&#8217; acontece neste domingo em clima de final da Copa do Mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#website","url":"https:\/\/www.blogsoestado.com\/evandrojunior\/","name":"Evandro Junior","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.blogsoestado.com\/evandrojunior\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/3e6c3d8dbb740d1c6878ebc935cfb3be","name":"Evandro Junior","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.blogsoestado.com\/evandrojunior\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f80a03a2294a580cd2318bfb459bf354cfa8be661ef3d95b542cf9a04af8d129?s=96&d=mm&r=g","caption":"Evandro Junior"},"url":"https:\/\/www.blogsoestado.com\/evandrojunior\/author\/evandrojunior\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/8155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/comments?post=8155"}],"version-history":[{"count":0,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/posts\/8155\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/media?parent=8155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/categories?post=8155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogsoestado.com\/evandrojunior\/wp-json\/wp\/v2\/tags?post=8155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}